{"id":1091,"date":"2020-09-10T15:40:55","date_gmt":"2020-09-10T15:40:55","guid":{"rendered":"https:\/\/www.ezoic.com\/fr-lang\/2020\/09\/10\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/"},"modified":"2020-09-10T15:40:55","modified_gmt":"2020-09-10T15:40:55","slug":"comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4","status":"publish","type":"post","link":"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/","title":{"rendered":"Comscore: Ce qu\u2019ils font et comment leur classement fonctionne (en r\u00e9alit\u00e9)"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_67_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\">Sommaire<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a56f2a1b7a4c\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a56f2a1b7a4c\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Que_fait_Comscore\" title=\"Que fait Comscore ?\">Que fait Comscore ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Quels_sont_les_classements_Comscore_et_comment_fonctionnent-ils\" title=\"Quels sont les classements Comscore et comment fonctionnent-ils ?\">Quels sont les classements Comscore et comment fonctionnent-ils ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Les_classements_Comscore_sont-ils_quelque_chose_qui_interesse_les_annonceurs_et_les_editeurs\" title=\"Les classements Comscore sont-ils quelque chose qui int\u00e9resse les annonceurs et les \u00e9diteurs ?\">Les classements Comscore sont-ils quelque chose qui int\u00e9resse les annonceurs et les \u00e9diteurs ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Que_mesure_le_Comite_Comscore\" title=\"Que mesure le Comit\u00e9 Comscore ?\">Que mesure le Comit\u00e9 Comscore ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Qui_ou_quest-ce_qui_compose_les_panneaux_Comscore\" title=\"Qui ou qu&#8217;est-ce qui compose les panneaux Comscore?\">Qui ou qu&#8217;est-ce qui compose les panneaux Comscore?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Quelle_est_lefficacite_du_systeme_de_mesure_des_panneaux_de_Comscore\" title=\"Quelle est l\u2019efficacit\u00e9 du syst\u00e8me de mesure des panneaux de Comscore ?\">Quelle est l\u2019efficacit\u00e9 du syst\u00e8me de mesure des panneaux de Comscore ?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Pourquoi_les_chiffres_de_trafic_Comscore_sont-ils_inferieurs_a_ceux_de_Google_Analytics\" title=\"Pourquoi les chiffres de trafic Comscore sont-ils inf\u00e9rieurs \u00e0 ceux de Google Analytics ?\">Pourquoi les chiffres de trafic Comscore sont-ils inf\u00e9rieurs \u00e0 ceux de Google Analytics ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Pourquoi_les_reseaux_publicitaires_sassocient-ils_a_Comscore\" title=\"Pourquoi les r\u00e9seaux publicitaires s\u2019associent-ils \u00e0 Comscore ?\">Pourquoi les r\u00e9seaux publicitaires s\u2019associent-ils \u00e0 Comscore ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Quest-ce_quune_lettre_daffectation_de_trafic_et_pourquoi_certains_reseaux_publicitaires_vous_demandent-ils_den_signer_une\" title=\"Qu\u2019est-ce qu\u2019une lettre d\u2019affectation de trafic, et pourquoi certains r\u00e9seaux publicitaires vous demandent-ils d\u2019en signer une ?\">Qu\u2019est-ce qu\u2019une lettre d\u2019affectation de trafic, et pourquoi certains r\u00e9seaux publicitaires vous demandent-ils d\u2019en signer une ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Y_a-t-il_des_inconvenients_a_signer_votre_trafic_vers_une_entite_Comscore\" title=\"Y a-t-il des inconv\u00e9nients \u00e0 signer votre trafic vers une entit\u00e9 Comscore ?\">Y a-t-il des inconv\u00e9nients \u00e0 signer votre trafic vers une entit\u00e9 Comscore ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Que_peuvent_faire_les_editeurs_pour_proteger_la_valeur_de_leur_audience\" title=\"Que peuvent faire les \u00e9diteurs pour prot\u00e9ger la valeur de leur audience ?\">Que peuvent faire les \u00e9diteurs pour prot\u00e9ger la valeur de leur audience ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Comscore_sera-t-il_aussi_important_pour_les_annonceurs_a_lavenir\" title=\"Comscore sera-t-il aussi important pour les annonceurs \u00e0 l\u2019avenir ?\">Comscore sera-t-il aussi important pour les annonceurs \u00e0 l\u2019avenir ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/#Conclusion\" title=\"Conclusion\">Conclusion<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Que_fait_Comscore\"><\/span>Que fait Comscore ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Comscore est une soci\u00e9t\u00e9 mondiale de mesure et d\u2019analyse des m\u00e9dias. Ils offrent une mesure en tiers parti de la d\u00e9mographie et de la performance de l\u2019auditoire pour les m\u00e9dias sur plusieurs supports. De leur propre d\u00e9finition;<\/p>\n<blockquote><p><a href=\"https:\/\/www.comscore.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Comscore<\/a> est un partenaire de confiance pour la planification, la transaction et l\u2019\u00e9valuation des m\u00e9dias sur les plates-formes. Avec la science data transformatrice et de vastes perspectives d\u2019audience \u00e0 travers le num\u00e9rique, la t\u00e9l\u00e9vision lin\u00e9aire, over-the-top (OTT) et le public th\u00e9\u00e2tral, nous sommes une source tierce puissante pour une mesure fiable des audiences multi-plateformes.<\/p><\/blockquote>\n<p>L\u2019id\u00e9e derri\u00e8re le suivi de l\u2019audience tiers est d\u2019apporter la transparence aux m\u00e9dias et au marketing, afin que les entreprises puissent utiliser les donn\u00e9es pour stimuler la croissance.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-246538\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/comscore-logo.jpg\" alt=\"Logo Comscore\" width=\"1000\" height=\"525\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quels_sont_les_classements_Comscore_et_comment_fonctionnent-ils\"><\/span>Quels sont les classements Comscore et comment fonctionnent-ils ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les classements de Comscore sont fond\u00e9s sur les services de mesure de l\u2019audience qu\u2019ils vendent\/fournissent aux \u00e9diteurs. La Comscore Media Matrix, accr\u00e9dit\u00e9e en 2016 par le <a role=\"link\" href=\"http:\/\/mediaratingcouncil.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Media Rating Council (MRC),<\/a> utilise une s\u00e9rie de \u00ab panels \u00bb pour mesurer les audiences.<\/p>\n<p>Ces services de mesure de l\u2019audience sont souvent observ\u00e9s par les annonceurs et les agences. Le principal facteur de diff\u00e9renciation entre Comscore et d\u2019autres solutions d\u2019analyse web (comme Google Analytics) est que leur objectif principal est de mesurer exactement qui est le public en question et le comportement de consommation. Il faut une fa\u00e7on un peu plus traditionnelle pour observer les visiteurs humains puisque de nombreux m\u00e9canismes de suivi des auditoires \u00e0 travers la t\u00e9l\u00e9vision et d\u2019autres m\u00e9dias sont moins objectifs que le num\u00e9rique. En outre, leur m\u00e9thode globale d\u00e9finit les pages vues sur tous les sites.<\/p>\n<p>Cela dit, les m\u00e9thodes et les techniques de mesure utilis\u00e9es par ComScore, et leur concurrent Neilson, comptent tous deux beaucoup sur la participation volontaire de toutes les parties \u00e0 l\u2019\u00e9cosyst\u00e8me pour fournir leur notation composite. Cela signifie que les auditoires, les \u00e9diteurs et les agences\/annonceurs doivent tous se plier \u00e0 la volont\u00e9 de ces tiers-partis s\u2019ils veulent participer \u00e0 ces syst\u00e8mes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-247085 size-full aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/d252fa40-4516-4643-8a5d-e9a145916008.jpeg\" alt=\"suivi comscore adtech\" width=\"777\" height=\"750\" \/><\/p>\n<p>Traditionnellement, le suivi des auditoires <a href=\"https:\/\/money.cnn.com\/2008\/09\/25\/technology\/hempel_comscore.fortune\/index.htm\" target=\"_blank\" rel=\"noopener\">n&#8217;a rencontr\u00e9 que de la critique<\/a>. Mais les r\u00e9centes acquisitions de grandes entreprises technologiques, comme Moat, ont d\u00e9montr\u00e9 la valeur du suivi \u00e0 travers l\u2019\u00e9cosyst\u00e8me; les \u00e9diteurs et les annonceurs s\u2019appuient depuis longtemps sur un arbitre pour la livraison de la campagne.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Les_classements_Comscore_sont-ils_quelque_chose_qui_interesse_les_annonceurs_et_les_editeurs\"><\/span>Les classements Comscore sont-ils quelque chose qui int\u00e9resse les annonceurs et les \u00e9diteurs ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les annonceurs et les \u00e9diteurs se soucient souvent des classements Comscore, mais pas comme on pourrait initialement supposer. La majorit\u00e9 des annonceurs n\u2019ont probablement aucune id\u00e9e de ce qu\u2019ils sont et accordent peu d\u2019attention \u00e0 ces services. Les agences et les 50 principaux \u00e9diteurs de marques accordent souvent beaucoup plus d\u2019attention \u00e0 ces mesures; comme ils sont g\u00e9n\u00e9ralement un point de discorde dans la n\u00e9gociation de contrats publicitaires. Comscore et leurs concurrents vivent comme un interm\u00e9diaire entre les deux.<\/p>\n<p>Si un \u00e9diteur n\u2019inclut pas les pixels Comscore sur ses pages (souvent parce qu\u2019il ralentit les sites et peut causer des erreurs), il ne sera pas comptabilis\u00e9 dans le classement de Comscore. Mais cela ne signifie pas r\u00e9ellement qu\u2019un annonceur ne ciblera pas un public sur son site&#8230;<\/p>\n<p>.<strong>.. Ainsi, les annonceurs qui utilisent Comscore lors de l\u2019achat par l\u2019interm\u00e9diaire d\u2019une agence cibleront toujours les audiences sur les sites d\u2019\u00e9diteurs qui n\u2019utilisent pas Comscore ou leurs concurrents.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-247091 size-full aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/013bcf1c-8897-4308-a1ff-f7c97432b0c0.jpeg\" alt=\"shakedown comscore\" width=\"1051\" height=\"720\" \/><\/p>\n<p>Alors, quel est le but si vous \u00eates un \u00e9diteur num\u00e9rique ? Cela d\u00e9pend des objectifs d\u2019un \u00e9diteur. Il y a peu d\u2019incitation mon\u00e9taire ou d\u2019avantage pour n\u2019importe qui du c\u00f4t\u00e9 de l&#8217;\u00e9diteur num\u00e9rique, selon l\u2019expert de l\u2019industrie \u00e0 qui vous demandez. Cependant, il s\u2019agit d\u2019un point de discorde concurrentiel parmi certaines des marques de m\u00e9dias de longue date qui d\u00e9pendaient de ces scores ou de ces classements pour les campagnes d\u2019achat de campagnes de t\u00e9l\u00e9vision.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Que_mesure_le_Comite_Comscore\"><\/span>Que mesure le Comit\u00e9 Comscore ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p class=\"q-text qu-display--block\">Les mesures du comit\u00e9 comprennent le <a href=\"https:\/\/www.comscore.com\/Insights\/Rankings\" target=\"_blank\" rel=\"noopener noreferrer\">classement Comscore<\/a>\u2014 une liste mensuelle des 50 premi\u00e8res propri\u00e9t\u00e9s num\u00e9riques sur le Web class\u00e9es par le nombre de visiteurs uniques du plus haut au plus bas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-246545\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/Screen-Shot-2020-08-04-at-2.36.45-PM-1024x649.png\" alt=\"Classement Comscore\" width=\"1024\" height=\"649\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Qui_ou_quest-ce_qui_compose_les_panneaux_Comscore\"><\/span>Qui ou qu&#8217;est-ce qui compose les panneaux Comscore?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les \u00ab pan\u00e9listes \u00bb sont identifi\u00e9s par Comscore comme des machines \u00e0 domicile ou au travail. Ceux-ci doivent \u00eatre personnellement d\u00e9tenus par le pan\u00e9liste (ou le m\u00e9nage) pour les qualifier en tant que pan\u00e9listes \u00e0 domicile. Les ordinateurs appartenant \u00e0 un employeur sont consid\u00e9r\u00e9s comme des ordinateurs de travail.<\/p>\n<p>Voici quelques exemples de choses que la m\u00e9thodologie du <a href=\"https:\/\/assets.pewresearch.org\/wp-content\/uploads\/sites\/13\/2014\/03\/comScore-Media-Metrix-Description-of-Methodology.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">panel<\/a> peut enregistrer comme des visites uniques :<\/p>\n<ul>\n<li>Activit\u00e9 Internet de toutes les entit\u00e9s Web, quel que soit le type de navigateur<\/li>\n<li>Sessions de navigation priv\u00e9es \/ Sessions s\u00e9curis\u00e9es<\/li>\n<li>\u00c9l\u00e9ments de contenu \/ streaming \/ messagerie instantan\u00e9e<\/li>\n<li>Technologies et protocoles bas\u00e9s sur le Web<\/li>\n<\/ul>\n<p>Le comit\u00e9 est ensuite pond\u00e9r\u00e9 et projet\u00e9 vers les r\u00e9seaucx Internet \u00e0 la maison et au travail aux \u00c9tats-Unis, ce qui permet de projeter le comportement des pan\u00e9listes aux populations d\u2019utilisateurs d\u2019Internet \u00e0 la maison ou au travail, aux \u00c9tats-Unis dans leur ensemble.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Quelle_est_lefficacite_du_systeme_de_mesure_des_panneaux_de_Comscore\"><\/span>Quelle est l\u2019efficacit\u00e9 du syst\u00e8me de mesure des panneaux de Comscore ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le syst\u00e8me de mesure des panneaux de Comscore semble \u00eatre pr\u00e9cis et efficace. Par curiosit\u00e9, j\u2019ai test\u00e9 les chiffres de Comscore pour une propri\u00e9t\u00e9 num\u00e9rique dans le Top 50 Comscore (Facebook.com) pour voir si le nombre enregistr\u00e9 de visiteurs uniques mensuels \u00e9tait comparable.<\/p>\n<p>Pour ce faire, je suis all\u00e9 \u00e0 l\u2019un des concurrents de Comscore, Similarweb. Le nombre de visiteurs am\u00e9ricains uniques sur le bureau de Facebook.com en juin 2020 \u00e9tait de 90,42 millions. Apr\u00e8s avoir croqu\u00e9 les chiffres, Similarweb \u00e9tait de 90,64 millions.<\/p>\n<p>Ils \u00e9taient tous les deux presque \u00e9gaux. Le fait que l\u2019attribution de Similarweb \u00e9tait l\u00e9g\u00e8rement plus \u00e9lev\u00e9e est tr\u00e8s probablement due au fait que les nombres que j\u2019ai utilis\u00e9s pour calculer ont \u00e9t\u00e9 arrondis jusqu\u2019\u00e0 la centi\u00e8me d\u00e9cimale, et non exactement.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-246919\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/comscore-data-comparison-scaled.jpg\" alt=\"Comparaison Comscore des visiteurs uniques mensuels\" width=\"341\" height=\"1024\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Pourquoi_les_chiffres_de_trafic_Comscore_sont-ils_inferieurs_a_ceux_de_Google_Analytics\"><\/span>Pourquoi les chiffres de trafic Comscore sont-ils inf\u00e9rieurs \u00e0 ceux de Google Analytics ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les chiffres de trafic Comscore sont inf\u00e9rieurs \u00e0 ceux de Google Analytics principalement en raison des diff\u00e9rences dans les m\u00e9thodologies de suivi. En voici quelques-unes des raisons :<\/p>\n<p><strong>Attribution:<\/strong> Google Analytics d\u00e9finit un <a href=\"https:\/\/support.google.com\/analytics\/answer\/2731565?hl=en#:~:text=How%20long%20does%20a%20session,starts%20counting%20from%20that%20moment.\" target=\"_blank\" rel=\"noopener noreferrer\">d\u00e9lai de session<\/a> comme 30 minutes d\u2019inactivit\u00e9. De plus, ils ont des r\u00e8gles d\u2019attribution additives. Cela signifie que 30 minutes d\u2019inactivit\u00e9 s\u2019ajoutent \u00e0 une nouvelle session. Comscore, d\u2019autre part, a une fen\u00eatre de 3 secondes pour se qualifier comme une visite. Tout ce qui a moins de 3 secondes conduit \u00e0 la disqualification.<\/p>\n<p><strong>Navigateurs multiples : <\/strong> Comscore \u00e9limine les visites de plusieurs navigateurs et \u00e9crans multiples (mobile, bureau, etc.)<\/p>\n<p><strong>Trafic non humain : <\/strong> Comscore ignore (ou \u00e9limine) le trafic de bots, et Google Analytics compte toutes les visites, qu\u2019il s\u2019agit d\u2019un bot ou d\u2019un utilisateur r\u00e9el. <strong>Cette diff\u00e9rence est le principal facteur \u00e0 l\u2019origine de la baisse du trafic de Comscore. Commentaire :<\/strong> Google offre maintenant un param\u00e8tre de filtrage de bots pour aider \u00e0 <a href=\"\/?p=245858\">\u00e9liminer le trafic non valide<\/a>.<\/p>\n<p><strong>Projection de donn\u00e9es : <\/strong> Pour l\u2019analyse, Google utilise les donn\u00e9es \u00ab en temps r\u00e9el \u00bb, puis enregistre et stocke les donn\u00e9es anonymes. Comscore fait des estimations bas\u00e9es sur le pool de pan\u00e9listes qui sont suivis via des plugins ou des cookies.<\/p>\n<blockquote><p>Un <a href=\"https:\/\/www.comscore.com\/esl\/Prensa-y-Eventos\/Presentaciones-y-libros-blancos\/2007\/Cookie-Deletion-Whitepaper\" target=\"_blank\" rel=\"noopener noreferrer\">rapport Comscore<\/a> a r\u00e9v\u00e9l\u00e9 que la suppression des cookies pourrait conduire \u00e0 des surestimations dans la mesure des serveurs de la taille des audiences en ligne. Sans ajustements, les rapports d\u2019audience des serveurs de site peuvent \u00eatre gonfl\u00e9s jusqu\u2019\u00e0 2,5 fois le nombre r\u00e9el de visiteurs uniques.<\/p><\/blockquote>\n<h2><span class=\"ez-toc-section\" id=\"Pourquoi_les_reseaux_publicitaires_sassocient-ils_a_Comscore\"><\/span>Pourquoi les r\u00e9seaux publicitaires s\u2019associent-ils \u00e0 Comscore ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La plupart des r\u00e9seaux publicitaires du top 50 de Comscore exigent des \u00e9diteurs qu\u2019ils affectent leur trafic par le biais d\u2019une lettre d\u2019affectation de trafic. Ce que cela fait, c\u2019est qu\u2019il ajoute votre trafic \u00e0 leur \u00ab total des visites uniques \u00bb et augmente finalement leur taille de propri\u00e9t\u00e9 Comscore.<\/p>\n<p class=\"p1\">Autrement dit, les r\u00e9seaux publicitaires et les plates-formes de gestion des annonces s\u2019associent \u00e0 Comscore parce qu\u2019ils peuvent tirer parti de votre trafic pour para\u00eetre \u00ab plus grand \u00bb. On va un peu d\u00e9composer \u00e7a.<\/p>\n<p class=\"p1\">De cette fa\u00e7on, quand ils essaient d\u2019attirer des agences, des annonceurs directs, etc., le public est grand. Cela vous profite en tant que partenaire, en supposant qu\u2019ils sont en mesure de tenir leurs promesses pour attirer ces types de grands annonceurs.<\/p>\n<p class=\"p1\">Du point de vue du r\u00e9seau publicitaire, vous ne serez probablement jamais en mesure de n\u00e9gocier de la m\u00eame fa\u00e7on qu\u2019un r\u00e9seau en serait capable pour vous. La plupart des r\u00e9seaux sont dans les milliards d\u2019impressions d\u2019annonces par mois, et c\u2019est donc ce qu\u2019ils veulent dire en disant que c&#8217;est ce que les annonceurs &#8220;recherchent&#8221;, quand ils veulent n\u00e9gocier.<\/p>\n<p class=\"intercom-align-left\">Pour ceux qui sont plus sceptiques, certains ont sp\u00e9cul\u00e9 que les r\u00e9seaux d\u2019annonces qui paient le prix annuel lourd qu\u2019il en co\u00fbte d\u2019avoir Comscore pour mesurer votre public <strong>veulent simplement para\u00eetre aussi grand que possible pour attirer le prochain \u00e9diteur dans leur pipeline d\u2019affaires. <\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quest-ce_quune_lettre_daffectation_de_trafic_et_pourquoi_certains_reseaux_publicitaires_vous_demandent-ils_den_signer_une\"><\/span>Qu\u2019est-ce qu\u2019une lettre d\u2019affectation de trafic, et pourquoi certains r\u00e9seaux publicitaires vous demandent-ils d\u2019en signer une ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Une lettre d\u2019affectation de trafic (TAL) est utilis\u00e9e pour affecter le trafic d\u2019un \u00e9diteur au r\u00e9seau avec lequel il travaille. Une fois ce trafic affect\u00e9, le r\u00e9seau publicitaire peut n\u00e9gocier des offres publicitaires pour le r\u00e9seau en g\u00e9n\u00e9ral et pour votre site web individuel. Plus le r\u00e9seau devient grand (aux yeux de Comscore \/ Quantcast \/ etc), mieux sont les offres qu\u2019ils sont en mesure de n\u00e9gocier. C\u2019est ce qui est pr\u00e9vu, du moins.<\/p>\n<blockquote><p>Les \u00e9diteurs oublient parfois qu\u2019ils ne peuvent affecter du trafic qu\u2019\u00e0 un seul endroit. La plupart des r\u00e9seaux publicitaires vous font g\u00e9n\u00e9ralement signer un contrat pour confirmer que vous avez officiellement sign\u00e9 sur votre trafic pour vivre sous l\u2019\u00e9gide de leur r\u00e9seau. En outre, vous <strong>ne pouvez pas signer <\/strong> d\u2019autres offres o\u00f9 vous signez votre trafic vers un ComScore etc. \u00e0 d\u2019autres tiers.<\/p><\/blockquote>\n<p>Vous trouverez ci-dessous un exemple de lettre d\u2019affectation de trafic Nielsen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-246877\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/traffic-assignment-policy.jpg\" alt=\"Lettre de politique d\u2019affectation de trafic\" width=\"1000\" height=\"789\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Y_a-t-il_des_inconvenients_a_signer_votre_trafic_vers_une_entite_Comscore\"><\/span>Y a-t-il des inconv\u00e9nients \u00e0 signer votre trafic vers une entit\u00e9 Comscore ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En surface, non. Et les r\u00e9seaux d\u2019annonces qui arrivent \u00e0 inclure vos chiffres de trafic mensuels dans leur nombre total de visiteurs uniques Comscore ne voudrait pas que vous le pensiez. Le but de tout cela est de para\u00eetre plus grand pour attirer de <em>plus grands<\/em> annonceurs. Mais parce que tout cela semble si simple et innocent, ils ne mentionnent pas les inconv\u00e9nients potentiels.<\/p>\n<p>L\u2019inconv\u00e9nient est que <strong>vous \u00e9liminez votre capacit\u00e9 \u00e0 diversifier certaines sources de revenus<\/strong><\/p>\n<p>Vous donnez (tr\u00e8s probablement) une plus grande partie de vos revenus au partenaire.<\/p>\n<p>Et le fait que vous ayiez sign\u00e9 un contrat d\u2019exclusivit\u00e9 ? Cela vous emp\u00eache de former d\u2019autres offres de r\u00e9seau. C\u2019est l\u2019une des raisons pour lesquelles <a href=\"\/?page_id=1148\">l\u2019Ad Tester<\/a>d\u2019Ezoic et toute notre plate-forme d\u2019ailleurs, a \u00e9t\u00e9 construite sur les piliers de la transparence, la valeur des tests fractionn\u00e9s, et pas de contrats. Mais qu\u2019est-ce que je veux dire exactement par tout \u00e7a ?<\/p>\n<blockquote><p><strong>Rappelez-vous: <\/strong> La plupart des accords TAL stipulent que la nouvelle propri\u00e9t\u00e9 num\u00e9rique (ou r\u00e9seau publicitaire) est <strong>maintenant le seul repr\u00e9sentant de votre site<\/strong>, et quels fournisseurs ils utilisent pour remplir tous les autres stocks (en dehors des ventes directes) que vous ne pouvez pas <strong>utiliser<\/strong>. Si le r\u00e9seau publicitaire conna\u00eet l\u2019industrie, ils utilisent tr\u00e8s probablement des fournisseurs premium et <strong>ne vous permettrony pas d\u2019ex\u00e9cuter le trafic par vous-m\u00eame<\/strong>, et au lieu de cela vont ex\u00e9cuter cet inventaire de publicit\u00e9 \u00e0 travers votre site \u00e0 une part de revenus sp\u00e9cifiques.<\/p><\/blockquote>\n<p><em><strong>Remarque :<\/strong> Cela peut ne pas \u00eatre vrai pour tous les r\u00e9seaux publicitaires, car chaque transaction est diff\u00e9rente. Mais de fa\u00e7on g\u00e9n\u00e9rale, ces aspects des lettres d\u2019affectation de la circulation sont vrais.<\/em><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Que_peuvent_faire_les_editeurs_pour_proteger_la_valeur_de_leur_audience\"><\/span>Que peuvent faire les \u00e9diteurs pour prot\u00e9ger la valeur de leur audience ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La meilleure chose que les \u00e9diteurs peuvent faire pour prot\u00e9ger la valeur de leur public est de <strong>toujours rester sceptique<\/strong>.<\/p>\n<p>Lisez les petits caract\u00e8res. Ne signez pas de contrats si vous avez la possibilit\u00e9 de les \u00e9viter. Demandez \u00e0 votre r\u00e9seau d\u2019annonces si vous pouvez fractionner et tester leur gestion d\u2019annonces par rapport \u00e0 un autre fournisseur.<\/p>\n<p>Parce qu\u2019en r\u00e9alit\u00e9, une comparaison sur le pied d&#8217;\u00e9galit\u00e9 est la seule fa\u00e7on de savoir savoir qui vous rapporte le plus de revenus. En raison de la<a href=\"\/?p=9620\"> saisonnalit\u00e9 des tarifs publicitaires, des<\/a>fluctuations de la demande publicitaire et des mises \u00e0 jour fr\u00e9quentes <a href=\"\/?p=241516\">de Google Core,<\/a>si vous testez un r\u00e9seau publicitaire dans un mois, puis un autre le mois suivant, ce n\u2019est pas une comparaison \u00e9quitable. Par cons\u00e9quent, vous ne saurez pas avec certitude qui \u00e9tait le meilleur.<\/p>\n<p>En r\u00e9alit\u00e9, il ya beaucoup de <a href=\"\/?p=12083\">joueurs escrocs dans l\u2019industrie de la publicit\u00e9<\/a> qui drainent l\u2019argent du pot. Pourtant, ces m\u00eames joueurs n\u2019ajoutent aucune valeur de retour. Un coup d\u2019\u0153il rapide \u00e0 l\u2019\u00c9cran Lumascape vous montrera \u00e0 quel point la technologie publicitaire est extr\u00eamement gonfl\u00e9e.<\/p>\n<p>Selon les recherches <a href=\"https:\/\/www.mediapost.com\/publications\/article\/270487\/study-finds-only-40-of-digital-buys-going-to-work.html\" target=\"_blank\" rel=\"noopener noreferrer\">par Technology Business Research<\/a>, pour chaque dollar d\u00e9pens\u00e9 sur la publicit\u00e9 programmatique, seulement <strong>40 centimes atteignent les consommateurs r\u00e9els. <\/strong>Donc, aussi incroyable que cela puisse para\u00eetre, 60 centimes (ou plus) de chaque dollar est englouti par l\u2019une des centaines d\u2019entit\u00e9s dans le tableau que vous voyez ci-dessous.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16488\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/lumascape-adtech.jpg\" alt=\"Afficher Lumascape\" width=\"1000\" height=\"750\" \/><\/p>\n<p>Il va donc sans dire, soyez prudent. Reconnaissez la valeur que vous avez en tant qu\u2019\u00e9diteur et prot\u00e9gez votre auditoire en interrogeant les choses et en restant sceptique.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comscore_sera-t-il_aussi_important_pour_les_annonceurs_a_lavenir\"><\/span>Comscore sera-t-il aussi important pour les annonceurs \u00e0 l\u2019avenir ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Beaucoup de gens ne le pensent pas. Au fil des ans, Comscore a re\u00e7u des retours (\u00e9loges et avis n\u00e9gatifs) mitig\u00e9s de publications en ligne, ainsi que dans des forums comme Reddit et Quora. La plainte la plus virulente ? Que l\u2019ensemble du mod\u00e8le d\u2019affaires de Comscore n\u2019est b\u00e9n\u00e9fique que pour les propri\u00e9t\u00e9s num\u00e9riques dans le top 50 Comscore.<\/p>\n<p>Certains incidents dans l\u2019histoire de Comscore donnent assez de poids \u00e0 ces sentiments n\u00e9gatifs.<\/p>\n<p>En 2010, apr\u00e8s des ann\u00e9es de plaintes contre Comscore, un scandale est survenu pour cause d&#8217;avoir sous-compter leur public (en raison de l\u2019utilisation <em><strong>pure<\/strong><\/em>d\u2019une mesure bas\u00e9e sur un panneau sans utiliser de pixels de suivi). Quantcast et Google les ont mis sous pression parce qu\u2019ils offrent des pixels de suivi <em><strong>gratuits<\/strong><\/em> via des sites qui pourraient compter leur trafic. Comscore <a href=\"https:\/\/www.comscore.com\/Insights\/Press-Releases\/2009\/5\/comScore-Announced-Media-Metrix-360?cs_edgescape_cc=US\" target=\"_blank\" rel=\"noopener noreferrer\">a ensuite \u00e9volu\u00e9 pour utiliser un mod\u00e8le \u00ab hybride \u00bb<\/a> de panneaux et de pixels de suivi c\u00f4t\u00e9 site.<\/p>\n<p>Par la suite, Comscore a donn\u00e9 le pixel de suivi gratuitement aux clients payants. Tout le monde \u00e9tait en col\u00e8re, parce qu\u2019ils ont d\u00fb payer Comscore 10 000 $ pour \u00e9viter de continuer \u00e0 avoir leur trafic compt\u00e9 de la fa\u00e7on pr\u00e9c\u00e9dente. En 2020, le paiement minimum pour utiliser les services de Comscore s\u2019\u00e9l\u00e8ve \u00e0 9 600 $ par ann\u00e9e.<\/p>\n<p>Depuis, leur stock est proche de son seuil le plus bas. L\u2019une des raisons de cette baisse peut remonter au troisi\u00e8me trimestre de 2019, lorsque la Securities and Exchange Commission <a href=\"https:\/\/www.sec.gov\/news\/press-release\/2019-186\" target=\"_blank\" rel=\"noopener noreferrer\">a accus\u00e9 l\u2019ancien PDG de Comscore de s\u2019\u00eatre<\/a> livr\u00e9 \u00e0 un <strong>stratag\u00e8me frauduleux visant \u00e0 surestimer les revenus d\u2019environ 50 millions de dollars et \u00e0 faire des d\u00e9clarations fausses et trompeuses sur les principales mesures<\/strong> de rendement.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-246865\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/comscore-stock-price.jpg\" alt=\"Prix de l\u2019action Comscore\" width=\"1000\" height=\"638\" \/><\/p>\n<p>Objectivement parlant, le bilan de Comscore n\u2019aide pas sa cause. Cela ne veut pas dire que ses outils de mesure ne sont pas pr\u00e9cieux, mais il vous fait vous demander;<\/p>\n<p>Les r\u00e9seaux publicitaires du Top 50 de Comscore arborent-ils purement le statut \u00ab Bigger is better \u00bb pour attirer les plus grands annonceurs ? Ou est-ce plus un argument de vente aux \u00e9diteurs potentiels de rejoindre leur r\u00e9seau ? Cela pourrait peut-\u00eatre \u00eatre un m\u00e9lange des deux.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclusion<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Il y a dix ans, Comscore \u00e9tait un signe d\u2019assurance que beaucoup d\u2019\u00e9diteurs et d\u2019annonceurs \u00e9taient heureux de rejoindre. Mais certains soutiennent que ceux du c\u00f4t\u00e9 de l\u2019annonceur ont toujours su que les classements Comscore et l\u2019efficacit\u00e9 de la campagne ne sont pas si rigoureusement li\u00e9s.<\/p>\n<p>De jour en jour, l\u2019\u00e9dition num\u00e9rique et l\u2019industrie de la publicit\u00e9 dans son ensemble sont davantage ax\u00e9es sur la performance. Ces classements ne sont tout simplement pas aussi importants qu\u2019ils l\u2019\u00e9taient autrefois. Ce qui est plus important de nos jours, c\u2019est le public lui-m\u00eame et la valeur qui cela repr\u00e9sente (directement) pour les annonceurs. Il y a tr\u00e8s peu de sc\u00e9narios o\u00f9 vous avez <em>besoin d\u2019un <\/em>grand r\u00e9seau publicitaire.<strong>Et<\/strong><strong>sp\u00e9cialement<\/strong> lorsque ce r\u00e9seau d\u2019annonces vous fait signer un contrat.<\/p>\n<p>Donc vous voyez comment les pi\u00e8ces du puzzle s&#8217;assemblent ici.<\/p>\n<p>Alors que les plus grands \u00e9diteurs pourraient trouver leurs services de mesure de l\u2019audience pr\u00e9cieux (m\u00eame \u00e0 leur prix cher), les classements Comscore eux-m\u00eames ne d\u00e9tiennent pas objectivement le m\u00eame poids qu\u2019il y a dix ans.<\/p>\n<p>Cela \u00e9tant dit, Comscore est toujours un grand nom et bien respect\u00e9 par beaucoup dans l\u2019espace publicitaire. Donc, si vous \u00eates un \u00e9diteur \u00e0 succ\u00e8s avec un large public, vous pouvez juger. C\u2019est votre public en fin de compte, et ne laissez jamais quiconque (personne ou r\u00e9seau publicitaire) essayer de vous convaincre un instant que vous avez besoin d\u2019eux pour r\u00e9ussir.<\/p>\n<p>Parce que c\u2019est si loin de la v\u00e9rit\u00e9. <strong>Ils ont besoin de vous. <\/strong><\/p>\n<p>Parce que sans vous, ils ne peuvent pas continuer \u00e0 devenir de plus en plus grand&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que fait Comscore ? Comscore est une soci\u00e9t\u00e9 mondiale de mesure et d\u2019analyse des m\u00e9dias. Ils offrent une mesure en tiers parti de la d\u00e9mographie et de la performance de l\u2019auditoire pour les m\u00e9dias sur plusieurs supports. De leur propre d\u00e9finition; Comscore est un partenaire de confiance pour la planification, la transaction et l\u2019\u00e9valuation des&hellip; <a class=\"more-link\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/comscore-ce-quils-font-et-comment-leur-classement-fonctionne-en-realite-4\/\">Continue reading <span class=\"screen-reader-text\">Comscore: Ce qu\u2019ils font et comment leur classement fonctionne (en r\u00e9alit\u00e9)<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[1],"tags":[8],"class_list":["post-1091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-fr","entry"],"_links":{"self":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts\/1091"}],"collection":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/comments?post=1091"}],"version-history":[{"count":0,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts\/1091\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/media\/1082"}],"wp:attachment":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/media?parent=1091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/categories?post=1091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/tags?post=1091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}