{"id":1575,"date":"2021-04-22T16:07:46","date_gmt":"2021-04-22T16:07:46","guid":{"rendered":"https:\/\/www.ezoic.com\/fr-lang\/2021\/04\/22\/le-pourcentage-des-revenus-annuels-que-les-editeurs-font-par-trimestre\/"},"modified":"2021-04-22T16:07:46","modified_gmt":"2021-04-22T16:07:46","slug":"le-pourcentage-des-revenus-annuels-que-les-editeurs-font-par-trimestre","status":"publish","type":"post","link":"https:\/\/wp.ezoic.com\/fr-lang\/le-pourcentage-des-revenus-annuels-que-les-editeurs-font-par-trimestre\/","title":{"rendered":"Le pourcentage des revenus annuels que les \u00e9diteurs font par trimestre"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.22&#8243;][et_pb_row admin_label=&#8221;ligne&#8221; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.7.5&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Le d\u00e9but du premier trimestre est g\u00e9n\u00e9ralement le moment o\u00f9 les tarifs publicitaires sont les plus bas. Historiquement, le revenu annuel d&#8217;un site Web n&#8217;est pas r\u00e9parti de mani\u00e8re \u00e9gale entre les trimestres, ce qui soul\u00e8ve la question suivante : quel pourcentage du revenu annuel les \u00e9diteurs gagnent-ils dans chaque trimestre respectif ?<\/p>\n<p>Malgr\u00e9 ce que 2020 a apport\u00e9, de nombreux \u00e9diteurs ont encore vu des taux publicitaires \u00e9lev\u00e9s au quatri\u00e8me trimestre. G\u00e9n\u00e9ralement, le Q4 sera une p\u00e9riode de revenus record pour les sites Web, car les taux d&#8217;annonces s&#8217;envolent et la plupart des \u00e9diteurs accumulent plus de revenus que tout autre trimestre. Mais dans quelle mesure le 4e trimestre est-il plus rentable que les autres trimestres, et \u00e0 quoi ressemblent les tendances en mati\u00e8re de revenus par trimestre ?<\/p>\n<p>Sur la base des donn\u00e9es de notre <a href=\"https:\/\/adrevenueindex.ezoic.com\/\" target=\"_blank\" rel=\"noopener\">Ad Revenue Index<\/a>, nous avons compil\u00e9 des informations sur le pourcentage de revenus que les \u00e9diteurs r\u00e9alisent, par trimestre, sur leurs revenus annuels.<\/p>\n<p>En regardant l&#8217;Ad Revenue Index, nous pouvons voir qu&#8217;il y a le m\u00eame sch\u00e9ma chaque ann\u00e9e ; il y a une grosse hausse autour de d\u00e9cembre, suivie d&#8217;une grosse baisse des revenus publicitaires au premier trimestre. Celui-ci augmente progressivement puis plonge au d\u00e9but de chaque nouveau trimestre, bien qu&#8217;il continue son ascension tout au long de l&#8217;ann\u00e9e.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-330168\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/Screen-Shot-2021-01-05-at-12.54.44-PM-copy.jpg\" alt=\"ad revenue index per year\" width=\"900\" height=\"513\" \/><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_67_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\">Sommaire<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a56d68e68616\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a56d68e68616\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/le-pourcentage-des-revenus-annuels-que-les-editeurs-font-par-trimestre\/#Revenus_publicitaires_du_1er_trimestre_vs_revenus_publicitaires_du_4e_trimestre\" title=\"Revenus publicitaires du 1er trimestre vs revenus publicitaires du 4e trimestre\">Revenus publicitaires du 1er trimestre vs revenus publicitaires du 4e trimestre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/le-pourcentage-des-revenus-annuels-que-les-editeurs-font-par-trimestre\/#Quand_les_sites_web_gagnent-ils_le_plus_grace_aux_publicites\" title=\"Quand les sites web gagnent-ils le plus gr\u00e2ce aux publicit\u00e9s ?\">Quand les sites web gagnent-ils le plus gr\u00e2ce aux publicit\u00e9s ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/le-pourcentage-des-revenus-annuels-que-les-editeurs-font-par-trimestre\/#Que_font_les_sites_web_lorsque_les_taux_de_publicite_baissent\" title=\"Que font les sites web lorsque les taux de publicit\u00e9 baissent ?\">Que font les sites web lorsque les taux de publicit\u00e9 baissent ?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Revenus_publicitaires_du_1er_trimestre_vs_revenus_publicitaires_du_4e_trimestre\"><\/span>Revenus publicitaires du 1er trimestre vs revenus publicitaires du 4e trimestre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Si nous examinons les donn\u00e9es de plus pr\u00e8s, nous pouvons constater que le pourcentage des revenus annuels que le 1er trimestre rapporte est g\u00e9n\u00e9ralement l&#8217;un des plus faibles et que le 2e trimestre est g\u00e9n\u00e9ralement un peu meilleur. Cela est suivi d&#8217;une diminution des revenus pour le T3 avant d&#8217;acc\u00e9l\u00e9rer \u00e0 nouveau lors des d\u00e9penses de consommation des f\u00eates de fin d&#8217;ann\u00e9e souvent observ\u00e9es au T4.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-330148\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/Screen-Shot-2021-01-05-at-10.21.42-AM.png\" alt=\"quarterly ad revenue per year\" width=\"703\" height=\"433\" \/><\/p>\n<p>L&#8217;ann\u00e9e 2017 et l&#8217;ann\u00e9e 2020 ont toutes deux contrari\u00e9 cette tendance commune.<\/p>\n<p>Les revenus publicitaires trimestriels par an sont en baisse.<\/p>\n<p>Voir plus de <a href=\"\/?p=330074\">tendances de 2020 pouvant s&#8217;appliquer \u00e0 2021 ici<\/a>.<\/p>\n<p>Les d\u00e9penses du troisi\u00e8me trimestre ont \u00e9t\u00e9 plus \u00e9lev\u00e9es que celles du deuxi\u00e8me trimestre au cours des deux ann\u00e9es ; c&#8217;\u00e9tait particuli\u00e8rement vrai pour 2020, o\u00f9 le premier trimestre a commenc\u00e9 \u00e0 des taux normaux, mais a ensuite chut\u00e9 lorsque le COVID-19 a balay\u00e9 le monde. Cela a ensuite \u00e9t\u00e9 <a href=\"\/?p=248009\">compens\u00e9 par des hausses des taux publicitaires au T3<\/a>, qui est g\u00e9n\u00e9ralement un trimestre plus lent pour les \u00e9diteurs, puis des taux publicitaires beaucoup plus \u00e9lev\u00e9s pour le T4, car les annonceurs ont affin\u00e9 les opportunit\u00e9s disponibles num\u00e9riquement avec leurs budgets publicitaires restants.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quand_les_sites_web_gagnent-ils_le_plus_grace_aux_publicites\"><\/span>Quand les sites web gagnent-ils le plus gr\u00e2ce aux publicit\u00e9s ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-330175\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/Screen-Shot-2021-01-05-at-1.38.43-PM.png\" alt=\"pourcentage du chiffre d'affaires annuel par trimestre\" width=\"699\" height=\"432\" \/><\/p>\n<p>Si nous examinons les pourcentages trimestriels moyens combin\u00e9s, nous pouvons constater que ces tendances ne sont pas tout \u00e0 fait les m\u00eames que lorsqu&#8217;elles sont ventil\u00e9es chaque ann\u00e9e. En fait, on peut dire sans risque de se tromper que chaque ann\u00e9e est un peu diff\u00e9rente, m\u00eame si nous pouvons trouver quelques similitudes g\u00e9n\u00e9rales auxquelles les \u00e9diteurs peuvent s&#8217;attendre.<\/p>\n<p>Il y a des g\u00e9n\u00e9ralit\u00e9s avec les \u00e9diteurs.<\/p>\n<p>Les g\u00e9n\u00e9ralit\u00e9s avec les revenus des \u00e9diteurs peuvent \u00eatre utiles d&#8217;un point de vue directionnel, mais comme il est souvent soulign\u00e9, les tarifs publicitaires peuvent varier \u00e9norm\u00e9ment selon les \u00e9diteurs &#8211; <a href=\"\/?p=243295\">m\u00eame s&#8217;ils ont un site web dans la m\u00eame cat\u00e9gorie, la m\u00eame niche<\/a>, et avec le m\u00eame trafic g\u00e9ographique qu&#8217;un autre site web<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-330154\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/Screen-Shot-2021-01-05-at-10.21.17-AM.png\" alt=\"pourcentages de revenus publicitaires trimestriels\" width=\"661\" height=\"407\" \/><\/p>\n<p>Sup\u00e9rieur, nous pouvons voir \u00e0 quel point les d\u00e9penses des T1 et T2 sont proches en moyenne, suivies d&#8217;une l\u00e9g\u00e8re hausse au T3, ce qui conduit ensuite au T4 qui repr\u00e9sente en moyenne le pourcentage le plus \u00e9lev\u00e9 de revenus. Cela peut \u00eatre une surprise pour certains sites Web qui peuvent voir plus de 50 % de leurs revenus annuels provenir de seulement 2 ou 3 mois \u00e0 la fin de l&#8217;ann\u00e9e.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Que_font_les_sites_web_lorsque_les_taux_de_publicite_baissent\"><\/span>Que font les sites web lorsque les taux de publicit\u00e9 baissent ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Comme le 4e trimestre rapporte le plus d&#8217;argent de tous les trimestres et que le 1er trimestre en rapporte le moins, cela peut \u00eatre d\u00e9stabilisant pour les \u00e9diteurs lorsque cette transition se produit. Cependant, cette baisse est normale et les \u00e9diteurs ne devraient g\u00e9n\u00e9ralement pas s&#8217;inqui\u00e9ter. Des opportunit\u00e9s existent pour les sites Web, <a href=\"\/?p=10337\">tant lorsque les taux de publicit\u00e9 sont \u00e9lev\u00e9s que lorsqu&#8217;ils sont bas<\/a>. L&#8217;\u00e9laboration d&#8217;une strat\u00e9gie sur la fa\u00e7on de tirer parti de ces changements peut faire partie de la planification annuelle et devrait \u00eatre analys\u00e9e avec soin avant que des changements massifs ne soient effectu\u00e9s.<\/p>\n<p>Nous avons couvert les m\u00e9canismes derri\u00e8re ces <a href=\"\/?p=10165\">flux et reflux saisonniers dans des articles pr\u00e9c\u00e9dents<\/a>s si vous souhaitez en savoir plus. De plus, c&#8217;est une p\u00e9riode o\u00f9 les principaux annonceurs \u00e9laborent des strat\u00e9gies et d\u00e9cident des budgets publicitaires pour le reste de l&#8217;ann\u00e9e.<\/p>\n<p>Les campagnes seront lanc\u00e9es en fonction de l&#8217;\u00e9volution de la demande.<\/p>\n<p>Les campagnes seront lanc\u00e9es tout au long du mois de janvier et continueront g\u00e9n\u00e9ralement leur mode cyclique \u00e0 partir de l\u00e0. Les annonceurs continueront probablement \u00e0 \u00eatre conservateurs car il y a encore de l&#8217;incertitude concernant COVID-19, donc les \u00e9diteurs pourraient voir des taux plus bas ce T1 que les ann\u00e9es pr\u00e9c\u00e9dentes ; cependant, 2020 a montr\u00e9 \u00e0 tous que <a href=\"\/?p=329843\">des p\u00e9riodes sans pr\u00e9c\u00e9dent pouvaient donner des r\u00e9sultats sans pr\u00e9c\u00e9dent<\/a> (et pas toujours de mani\u00e8re n\u00e9gative).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.22&#8243;][et_pb_row admin_label=&#8221;ligne&#8221; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.7.5&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;] Le d\u00e9but du premier trimestre est g\u00e9n\u00e9ralement le moment o\u00f9 les tarifs publicitaires sont les plus bas. Historiquement, le revenu annuel d&#8217;un site Web n&#8217;est pas r\u00e9parti de mani\u00e8re \u00e9gale entre les trimestres, ce qui&hellip; <a class=\"more-link\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/le-pourcentage-des-revenus-annuels-que-les-editeurs-font-par-trimestre\/\">Continue reading <span class=\"screen-reader-text\">Le pourcentage des revenus annuels que les \u00e9diteurs font par trimestre<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[1],"tags":[8],"class_list":["post-1575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-fr","entry"],"_links":{"self":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts\/1575"}],"collection":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/comments?post=1575"}],"version-history":[{"count":0,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts\/1575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/media\/1580"}],"wp:attachment":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/media?parent=1575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/categories?post=1575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/tags?post=1575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}