{"id":2431,"date":"2024-09-09T10:01:17","date_gmt":"2024-09-09T10:01:17","guid":{"rendered":"https:\/\/wp.ezoic.com\/fr-lang\/?p=2431"},"modified":"2024-09-23T10:37:14","modified_gmt":"2024-09-23T10:37:14","slug":"spo-inventaire-ezoic-dr-fou","status":"publish","type":"post","link":"https:\/\/wp.ezoic.com\/fr-lang\/spo-inventaire-ezoic-dr-fou\/","title":{"rendered":"L&#8217;inventaire de haute qualit\u00e9 d&#8217;Ezoic : SPO expliqu\u00e9 &amp; aper\u00e7u par le Dr. Augustine Fou, chercheur en ad fraud"},"content":{"rendered":"\n<p>Ezoic s&#8217;est donn\u00e9 pour mission d&#8217;aider les \u00e9diteurs \u00e0 \u00e9valuer correctement leurs espaces publicitaires. Cela signifiait aplanir le terrain de jeu dans lequel les annonceurs b\u00e9n\u00e9ficiaient jusqu&#8217;\u00e0 pr\u00e9sent de bien plus d&#8217;avantages syst\u00e9matiques. Mais fondamentalement, les deux parties partent du principe que la publicit\u00e9 en ligne a une r\u00e9elle valeur. L&#8217;environnement num\u00e9rique pose un certain nombre de d\u00e9fis \u00e0 cet \u00e9gard, car il existe un risque d&#8217;acteurs malveillants, de co\u00fbts cach\u00e9s et de v\u00e9ritables fraudes. C&#8217;est pourquoi nous avons toujours ax\u00e9 notre activit\u00e9 sur le maintien et la pr\u00e9servation de la valeur pour toutes les parties, m\u00eame lorsque cette approche n&#8217;\u00e9tait pas populaire ou particuli\u00e8rement rentable.<\/p>\n\n\n\n<p>Dans cette \u00e9tude de cas en deux parties, nous nous penchons d&#8217;abord sur le Supply Path Optimization (SPO) et le contr\u00f4le de qualit\u00e9 qu&#8217;Ezoic met en \u0153uvre pour maintenir des normes \u00e9lev\u00e9es et donner aux annonceurs la certitude que leurs campagnes atteignent des groupes cibles r\u00e9els et engag\u00e9s. Nous pr\u00e9sentons ensuite une interview exclusive du Dr Augustine Fou, l&#8217;un des chercheurs en fraude publicitaire les plus importants et les plus rigoureux de l&#8217;industrie, qui r\u00e9v\u00e8le ses connaissances expertes sur les raisons pour lesquelles le trafic d&#8217;Ezoic peut \u00eatre consid\u00e9r\u00e9 comme particuli\u00e8rement humain dans une industrie souvent en proie au trafic de bots et aux sources non valides. Cet article offre aux annonceurs une perspective pr\u00e9cieuse, bas\u00e9e sur des donn\u00e9es, sur les raisons pour lesquelles un partenariat avec Ezoic garantit que leurs annonces sont vues par de vrais utilisateurs et maximise l&#8217;impact de leurs campagnes.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_67_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\">Sommaire<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a56e19a23d0d\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a56e19a23d0d\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/spo-inventaire-ezoic-dr-fou\/#Partie_1_Assurance_qualite_de_loptimisation_du_parcours_dachat_SPO\" title=\"Partie 1 : Assurance qualit\u00e9 de l&#8217;optimisation du parcours d&#8217;achat (SPO)\">Partie 1 : Assurance qualit\u00e9 de l&#8217;optimisation du parcours d&#8217;achat (SPO)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/spo-inventaire-ezoic-dr-fou\/#Partie_2_Interview_du_Dr_Fou\" title=\"Partie 2 : Interview du Dr. Fou\">Partie 2 : Interview du Dr. Fou<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/spo-inventaire-ezoic-dr-fou\/#Conclusion\" title=\"Conclusion\">Conclusion<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Partie_1_Assurance_qualite_de_loptimisation_du_parcours_dachat_SPO\"><\/span>Partie 1 : Assurance qualit\u00e9 de l&#8217;optimisation du parcours d&#8217;achat (SPO)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En termes simples, l&#8217;optimisation du chemin d&#8217;approvisionnement (SPO) d\u00e9crit le processus par lequel les annonceurs et les plateformes c\u00f4t\u00e9 demande (DSP) cherchent le chemin le plus court et le plus rentable vers l&#8217;inventaire publicitaire. Les DSP utilisent des algorithmes en temps r\u00e9el pour faire des offres avec les chemins les plus courts et les plus efficaces vers les impressions \u00e0 acheter dans l&#8217;inventaire publicitaire des \u00e9diteurs. Les annonceurs \u00e9vitent ainsi des co\u00fbts inutiles et veillent \u00e0 ce que leurs annonces apparaissent sur des pages de qualit\u00e9. L&#8217;objectif de SPO est de garantir que le budget publicitaire est utilis\u00e9 de mani\u00e8re optimale en renfor\u00e7ant le lien direct avec les \u00e9diteurs pertinents.<\/p>\n\n\n\n<p>Les initiatives SPO d&#8217;Ezoic visent \u00e0 augmenter la valeur et l&#8217;efficacit\u00e9 de l&#8217;inventaire des sites web pour les annonceurs en \u00e9liminant les revendeurs qui n&#8217;apportent pas de valeur significative au flux d&#8217;ench\u00e8res. Si trop de demandes non rentables sont envoy\u00e9es \u00e0 travers le flux d&#8217;ench\u00e8res, elles peuvent surcharger les SSP (plateformes c\u00f4t\u00e9 offre) et les DSP (plateformes c\u00f4t\u00e9 demande), ce qui entra\u00eene un &#8220;shaping&#8221; des demandes. Comme les DSP ne peuvent traiter qu&#8217;un nombre limit\u00e9 de demandes d&#8217;ench\u00e8res par seconde, les SSP donnent la priorit\u00e9 aux offres dont ils pensent qu&#8217;elles donneront le meilleur r\u00e9sultat. Si trop de demandes de mauvaise qualit\u00e9 sont envoy\u00e9es, il y a un risque que m\u00eame les demandes potentiellement int\u00e9ressantes soient filtr\u00e9es, ce qui r\u00e9duit les chances d&#8217;obtenir des ench\u00e8res \u00e9lev\u00e9es et, en fin de compte, affecte les performances de la campagne.<\/p>\n\n\n\n<p>En excluant les revendeurs inutiles et en rationalisant les connexions directement avec les meilleurs SSP, annonceurs et DSP, Ezoic s&#8217;assure que, de la demande d&#8217;ench\u00e8re \u00e0 la diffusion de l&#8217;annonce, seul le chemin le plus qualitatif et le plus direct entre le site et l&#8217;annonceur est utilis\u00e9. Cela am\u00e9liore non seulement l&#8217;efficience et l&#8217;efficacit\u00e9 des campagnes publicitaires, mais garantit \u00e9galement que les budgets des annonceurs sont utilis\u00e9s de mani\u00e8re r\u00e9fl\u00e9chie, sans que des interm\u00e9diaires inutiles n&#8217;en d\u00e9tournent une partie. En outre, la r\u00e9duction des millions de lignes ads.txt de ces interm\u00e9diaires dans l&#8217;ensemble de notre portefeuille assure une plus grande transparence et , accessoirement, r\u00e9duit les \u00e9missions de CO2.<\/p>\n\n\n\n<p>En combinaison avec nos processus rigoureux d&#8217;assurance qualit\u00e9, qui impliquent \u00e0 la fois une IA avanc\u00e9e et une \u00e9quipe d\u00e9di\u00e9e \u00e0 la qualit\u00e9 des plateformes, les annonceurs peuvent \u00eatre s\u00fbrs que leurs publicit\u00e9s atteindront des audiences organiques engag\u00e9es sur des sites web de haute qualit\u00e9. Cette approche fait d&#8217;Ezoic un partenaire fiable pour fournir des performances optimales et maximiser le retour sur investissement des annonceurs, tout en augmentant les RPM des \u00e9diteurs sur la plateforme Ezoic, ce qui se traduit par <a href=\"\/fr-lang\/ezoicads\/\" class=\"ek-link\">des revenus plus \u00e9lev\u00e9s avec moins d&#8217;annonces<\/a>. Ne vous fiez pas seulement \u00e0 notre parole, mais &#8220;voyez Fou vous-m\u00eame&#8221; dans notre derni\u00e8re interview du <a href=\"https:\/\/www.linkedin.com\/in\/augustinefou\/\" class=\"ek-link\" target=\"_blank\" rel=\"noopener\">Dr Augustine Fou<\/a>, l&#8217;un des plus grands chercheurs en mati\u00e8re de fraude publicitaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Partie_2_Interview_du_Dr_Fou\"><\/span>Partie 2 : Interview du Dr. Fou<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>L&#8217;interview a \u00e9t\u00e9 anim\u00e9e par Alyssa Mitzel, sp\u00e9cialiste du marketing produit chez Ezoic :<\/p>\n\n\n\n<p><strong>Alyssa : Dr Fou, pouvez-vous nous donner un bref aper\u00e7u de votre exp\u00e9rience dans le domaine de la fraude publicitaire et de l&#8217;importance de l&#8217;identification du trafic de qualit\u00e9 dans le secteur publicitaire actuel ?<\/strong><\/p>\n\n\n\n<p>Dr Fou : <em>Je m&#8217;occupe d&#8217;ad fraud depuis presque 13 ans, depuis que j&#8217;ai quitt\u00e9 Omnicom en 2012. \u00c0 l&#8217;\u00e9poque, de simples robots chargeaient des pages web pour que des impressions publicitaires soient g\u00e9n\u00e9r\u00e9es et que l&#8217;on soit pay\u00e9 au CPM. Les robots cliquaient \u00e9galement sur les annonces, par exemple les annonces de recherche, pour aider les sites Web frauduleux \u00e0 gagner de l&#8217;argent sur la base du CPC (co\u00fbt par clic). Les bots sont devenus de plus en plus avanc\u00e9s, il est donc important de toujours rester vigilant et d&#8217;utiliser des analyses qui vous montrent plus de d\u00e9tails qu&#8217;un simple pourcentage de &#8220;trafic invalide&#8221; (%IVT). De cette mani\u00e8re, vous pouvez comprendre pourquoi quelque chose a \u00e9t\u00e9 marqu\u00e9 comme un bot ou, plus important encore, pourquoi il n&#8217;a PAS \u00e9t\u00e9 marqu\u00e9 comme un bot ou une fraude.<\/em><\/p>\n\n\n\n<p><strong>Alyssa : Comment \u00e9valuez-vous habituellement la qualit\u00e9 du trafic d&#8217;un site ou d&#8217;une plate-forme ? Quels sont les indicateurs cl\u00e9s que vous recherchez et qui indiquent un trafic humain de qualit\u00e9 ?<\/strong><\/p>\n\n\n\n<p>Dr Fou : <em>Dans FouAnalytics, nous ne mesurons pas seulement les robots et le trafic non valide, mais aussi les humains. La raison en est que l&#8217;absence de trafic de bots d\u00e9tect\u00e9 ne signifie pas n\u00e9cessairement qu&#8217;il s&#8217;agit de personnes. Lorsque les fournisseurs traditionnels de solutions de v\u00e9rification de la fraude signalent 1 % de trafic non valide, la plupart des gens supposent simplement que les 99 % restants sont humains. Ils doivent toutefois \u00eatre conscients que la plupart de ces 99 % pourraient ne pas \u00eatre mesurables ou tout simplement non mesur\u00e9s (par exemple parce que les bots bloquent les balises de d\u00e9tection des anciens fournisseurs). C&#8217;est pourquoi ils n&#8217;ont pas pu marquer le bot comme IVT. Il ne faut donc pas partir du principe que les 99 % restants sont des personnes. <\/em><\/p>\n\n\n\n<p><em>Ils doivent mesurer positivement pour les humains, comme le fait FouAnalytics. Dans les diagrammes de FouAnalytics, le bleu fonc\u00e9 signifie des personnes et le rouge fonc\u00e9 signifie des bots confirm\u00e9s. Le graphique ci-dessous montre des donn\u00e9es Ezoic \u00e0 l&#8217;\u00e9chelle de la plate-forme ; il montre une grande quantit\u00e9 de bleu fonc\u00e9 (personnes) et une petite quantit\u00e9 de rouge fonc\u00e9 (5 %). Le nombre de bots ne sera jamais de 0 %, car tout site web public peut \u00eatre acc\u00e9d\u00e9 par des bots \u00e0 tout moment. La cl\u00e9 est de surveiller avec des analyses d\u00e9taill\u00e9es afin de voir quels sont les bots, d&#8217;o\u00f9 ils viennent et pourquoi ils sont l\u00e0.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/wp.ezoic.com\/de-lang\/wp-content\/uploads\/2024\/09\/image-2.png\" alt=\"ezoic chart.png\" class=\"wp-image-340719\" title=\"ezoic chart.png\"\/><\/figure>\n\n\n\n<p><strong>Alyssa : Comment le trafic d&#8217;Ezoic se situe-t-il dans vos analyses par rapport aux normes du secteur ? Pourriez-vous partager des donn\u00e9es ou des m\u00e9triques sp\u00e9cifiques qui ont \u00e9t\u00e9 mises en \u00e9vidence lors de votre \u00e9valuation ?<\/strong><\/p>\n\n\n\n<p>Dr Fou : <em>Pour les sources d&#8217;offres comme Ezoic, il est important de v\u00e9rifier les sites web avant de les inclure dans le r\u00e9seau et de les surveiller en permanence pour d\u00e9tecter toute activit\u00e9 suspecte, comme l&#8217;achat de trafic. C&#8217;est pr\u00e9cis\u00e9ment pour cela qu&#8217;Ezoic utilise FouAnalytics depuis des ann\u00e9es. Et les couleurs du graphique ci-dessus sont la preuve du travail acharn\u00e9 et de la vigilance de l&#8217;\u00e9quipe d&#8217;Ezoic. Les efforts de SPO et d&#8217;assurance qualit\u00e9 mentionn\u00e9s ci-dessus sont essentiels, et l&#8217;utilisation de la bonne plate-forme d&#8217;analyse, qui vous donne les d\u00e9tails pour comprendre s&#8217;il s&#8217;agit d&#8217;un trafic de bots non valide ou de visiteurs humains, signifie qu&#8217;Ezoic peut v\u00e9rifier efficacement les sites web avant qu&#8217;ils ne soient accept\u00e9s sur le r\u00e9seau (environ 87 % de l&#8217;ensemble des candidatures pour Ezoic sont rejet\u00e9es) et continuer \u00e0 surveiller le r\u00e9seau pour d\u00e9tecter toute activit\u00e9 frauduleuse ou suspecte.<\/em><\/p>\n\n\n\n<p><em>Gr\u00e2ce aux graphiques FouAnalytics, la plateforme Ezoic peut non seulement montrer aux acheteurs d&#8217;annonces qu&#8217;il y a un faible IVT, mais aussi qu&#8217;il y a de grandes quantit\u00e9s d&#8217;espace bleu fonc\u00e9 &#8211; c&#8217;est-\u00e0-dire des groupes cibles humains. Pour les annonceurs qui tiennent \u00e0 ce que leurs annonces atteignent de vraies personnes, c&#8217;est un bon point de d\u00e9part. Il vaut vraiment la peine de payer un CPM plus \u00e9lev\u00e9 pour cet inventaire de qualit\u00e9 que pour des tonnes d&#8217;inventaire de moindre qualit\u00e9 ailleurs. <\/em><\/p>\n\n\n\n<p><strong>Alyssa : D&#8217;apr\u00e8s ce que vous avez constat\u00e9 avec FouAnalytics, qu&#8217;est-ce qui rend le trafic d&#8217;Ezoic particuli\u00e8rement &#8220;tr\u00e8s humain&#8221; et &#8220;tr\u00e8s actif&#8221; ? Pourriez-vous expliquer en quoi cela contraste avec les probl\u00e8mes habituels tels que le trafic de bots ou les sources de trafic non valides ?<\/strong><\/p>\n\n\n\n<p>Dr Fou : <em>Les annonceurs ne doivent m\u00eame pas seulement se fier au fait que nous avons correctement identifi\u00e9 les personnes (comme \u00e9tant en bleu fonc\u00e9). Les donn\u00e9es de FouAnalytics montrent que les visiteurs des sites web sur la plateforme Ezoic sont \u00e9galement actifs sur le site. Les donn\u00e9es ci-dessous sur les utilisateurs mobiles montrent par exemple que 84 \u00e0 86 % d&#8217;entre eux ont touch\u00e9 l&#8217;\u00e9cran, 44 \u00e0 52 % ont d\u00e9plac\u00e9 la souris et 42 \u00e0 51 % ont cliqu\u00e9 sur quelque chose sur la page. De toute \u00e9vidence, les gens doivent regarder l&#8217;\u00e9cran de leur smartphone pour faire ces choses. Cela signifie qu&#8217;ils pr\u00eatent \u00e9galement &#8220;attention&#8221; \u00e0 la publicit\u00e9 sur la page. Pour les annonceurs qui utilisent &#8220;l&#8217;attention&#8221; comme indicateur, nous pouvons le montrer dans les donn\u00e9es, de sorte qu&#8217;ils ne doivent pas se fier uniquement \u00e0 notre parole. En outre, aucun des fournisseurs de v\u00e9rification traditionnels ne peut pr\u00e9senter ces donn\u00e9es. En revanche, le trafic des bots sur les pages web ne montre pratiquement aucune activit\u00e9 comme celle-ci, car d\u00e8s que le bot charge la page web, les annonces sont charg\u00e9es ; les bots ne perdent donc pas de temps \u00e0 interagir sur la page. Ils quittent la page aussi vite que possible afin de pouvoir charger la page suivante de mani\u00e8re frauduleuse.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/wp.ezoic.com\/de-lang\/wp-content\/uploads\/2024\/09\/image-3.png\" alt=\"touch charts.png\" class=\"wp-image-340720\" title=\"touch charts.png\"\/><\/figure>\n\n\n\n<p><em>Les annonceurs qui souhaitent diffuser des annonces pour des groupes cibles humains devraient obtenir des preuves de chaque source d&#8217;approvisionnement, comme nous l&#8217;avons fait ci-dessus pour la qualit\u00e9 et &#8220;l&#8217;humanit\u00e9&#8221; du groupe cible sur la plate-forme Ezoic. Les donn\u00e9es susmentionn\u00e9es ont \u00e9t\u00e9 mesur\u00e9es &#8220;sur le terrain&#8221;. Les annonceurs peuvent s&#8217;en rendre compte par eux-m\u00eames lorsqu&#8217;ils ach\u00e8tent des annonces aupr\u00e8s d&#8217;Ezoic, en ins\u00e9rant des tags in-ad dans leur ad server ou leur DSP. <\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclusion<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Cette \u00e9tude de cas montre comment Ezoic se distingue des autres plateformes par son engagement en faveur de la qualit\u00e9 et de la transparence dans le secteur de la publicit\u00e9 num\u00e9rique pour les annonceurs. L&#8217;accent que nous mettons sur l&#8217;optimisation de l&#8217;ensemble du parcours d&#8217;approvisionnement, de la demande d&#8217;ench\u00e8re \u00e0 la diffusion de l&#8217;annonce, permet d&#8217;obtenir des campagnes plus efficaces et plus percutantes. La confirmation et la validation par le Dr Augustine Fou ont \u00e9galement d\u00e9montr\u00e9 que le trafic d&#8217;Ezoic est non seulement exempt de fraude, mais aussi tr\u00e8s humain et actif, ce qui est rare sur le march\u00e9 actuel.<\/p>\n\n\n\n<p><a href=\"\/fr-lang\/direct-deals\/\" class=\"ek-link\">Pour les annonceurs<\/a>, la valeur d&#8217;une collaboration avec Ezoic va au-del\u00e0 de simples m\u00e9triques &#8211; nous offrons un aper\u00e7u bas\u00e9 sur des donn\u00e9es et un engagement \u00e0 fournir des audiences authentiques et r\u00e9actives. En se concentrant sur la qualit\u00e9 plut\u00f4t que sur la quantit\u00e9 et en surveillant activement le trafic pour garantir un v\u00e9ritable engagement humain, Ezoic permet aux annonceurs d&#8217;<a href=\"\/fr-lang\/direct-deals\/\" class=\"ek-link\">investir en toute confiance dans un inventaire<\/a> qui produit de v\u00e9ritables r\u00e9sultats.<\/p>\n\n\n\n<script defer src=\"https:\/\/i.emote.com\/js\/emote.js\"><\/script>\n<div id=\"emote_com\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ezoic s&#8217;est donn\u00e9 pour mission d&#8217;aider les \u00e9diteurs \u00e0 \u00e9valuer correctement leurs espaces publicitaires. Cela signifiait aplanir le terrain de jeu dans lequel les annonceurs b\u00e9n\u00e9ficiaient jusqu&#8217;\u00e0 pr\u00e9sent de bien plus d&#8217;avantages syst\u00e9matiques. Mais fondamentalement, les deux parties partent du principe que la publicit\u00e9 en ligne a une r\u00e9elle valeur. L&#8217;environnement num\u00e9rique pose un certain&hellip; <a class=\"more-link\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/spo-inventaire-ezoic-dr-fou\/\">Continue reading <span class=\"screen-reader-text\">L&#8217;inventaire de haute qualit\u00e9 d&#8217;Ezoic : SPO expliqu\u00e9 &amp; aper\u00e7u par le Dr. Augustine Fou, chercheur en ad fraud<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":2438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[12,14],"tags":[],"class_list":["post-2431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-du-secteur","category-conseils-ezoic","entry"],"_links":{"self":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts\/2431"}],"collection":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/comments?post=2431"}],"version-history":[{"count":3,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts\/2431\/revisions"}],"predecessor-version":[{"id":2439,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts\/2431\/revisions\/2439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/media\/2438"}],"wp:attachment":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/media?parent=2431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/categories?post=2431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/tags?post=2431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}