{"id":270,"date":"2019-06-04T11:12:04","date_gmt":"2019-06-04T11:12:04","guid":{"rendered":"https:\/\/www.ezoic.com\/fr-lang\/2019\/06\/04\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/"},"modified":"2019-06-04T11:12:04","modified_gmt":"2019-06-04T11:12:04","slug":"quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web","status":"publish","type":"post","link":"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/","title":{"rendered":"Quels plugins WordPress et th\u00e8mes peuvent acc\u00e9l\u00e9rer votre site Web?"},"content":{"rendered":"<p>[et_pb_section bb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221;][et_pb_row admin_label=&#8221;row&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221; _builder_version=&#8221;3.21.4&#8243; z_index_tablet=&#8221;500&#8243;]<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_67_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\">Sommaire<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a56d665903b9\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a56d665903b9\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Quels_plugins_WordPress_et_themes_peuvent_accelerer_votre_site_Web\" title=\"Quels plugins WordPress et th\u00e8mes peuvent acc\u00e9l\u00e9rer votre site Web?\">Quels plugins WordPress et th\u00e8mes peuvent acc\u00e9l\u00e9rer votre site Web?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Ce_que_nous_savons_sur_WordPress_et_les_scores_de_vitesse_du_site\" title=\"Ce que nous savons sur WordPress et les scores de vitesse du site\">Ce que nous savons sur WordPress et les scores de vitesse du site<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Quels_themes_WordPress_sont_les_plus_lents\" title=\"Quels th\u00e8mes WordPress sont les plus lents?\">Quels th\u00e8mes WordPress sont les plus lents?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Quels_themes_WordPress_sont_les_plus_rapides\" title=\"Quels th\u00e8mes WordPress sont les plus rapides?\">Quels th\u00e8mes WordPress sont les plus rapides?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Quels_plugins_peuvent_etre_utilises_pour_rendre_un_site_Web_plus_rapide\" title=\"Quels plugins peuvent \u00eatre utilis\u00e9s pour rendre un site Web plus rapide?\">Quels plugins peuvent \u00eatre utilis\u00e9s pour rendre un site Web plus rapide?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Comment_utiliser_WP-Rocket_pour_rendre_votre_site_web_plus_rapide\" title=\"Comment utiliser WP-Rocket pour rendre votre site web plus rapide\">Comment utiliser WP-Rocket pour rendre votre site web plus rapide<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Comment_utiliser_WP_Disable_pour_rendre_votre_site_web_plus_rapide\" title=\"Comment utiliser WP Disable pour rendre votre site web plus rapide\">Comment utiliser WP Disable pour rendre votre site web plus rapide<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Comment_utiliser_Asset_CleanUp_Pro_pour_rendre_votre_site_Web_plus_rapide\" title=\"Comment utiliser Asset CleanUp Pro pour rendre votre site Web plus rapide\">Comment utiliser Asset CleanUp Pro pour rendre votre site Web plus rapide<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Utilisation_de_ShortPixel_pour_servir_des_images_dans_des_formats_next-gen\" title=\"Utilisation de ShortPixel pour servir des images dans des formats next-gen\">Utilisation de ShortPixel pour servir des images dans des formats next-gen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Utilisation_dEzoic_pour_simplifier_la_vitesse_du_site_WordPress\" title=\"Utilisation d&#8217;Ezoic pour simplifier la vitesse du site WordPress\">Utilisation d&#8217;Ezoic pour simplifier la vitesse du site WordPress<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Les_sites_ezoiques_sont_en_moyenne_plus_rapides_que_les_sites_en_haut\" title=\"Les sites \u00e9zo\u00efques sont en moyenne plus rapides que les sites en haut\">Les sites \u00e9zo\u00efques sont en moyenne plus rapides que les sites en haut<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/#Rendre_votre_site_Web_WordPress_rapide\" title=\"Rendre votre site Web WordPress rapide\">Rendre votre site Web WordPress rapide<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Quels_plugins_WordPress_et_themes_peuvent_accelerer_votre_site_Web\"><\/span>Quels plugins WordPress et th\u00e8mes peuvent acc\u00e9l\u00e9rer votre site Web?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Continuez-vous \u00e0 recevoir des rapports pagespeed qui montrent que votre site Web pourrait \u00eatre plus rapide? Vous et tous ceux qui poss\u00e8dent un site Web. En analysant les scores mobiles Pagespeed Insights de Google pour les grands \u00e9diteurs de l&#8217;ensemble du web, nous avons appris que le score moyen de vitesse mobile \u00e9tait inf\u00e9rieur \u00e0 24 sur 100.<\/p>\n<figure id=\"attachment_7350\" aria-describedby=\"caption-attachment-7350\" style=\"width: 408px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7350 size-full\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-04-29T161102.992-min.png\" alt=\"score de vitesse site wordpress\" width=\"408\" height=\"504\"><figcaption id=\"caption-attachment-7350\" class=\"wp-caption-text\"><span style=\"color: #808080\"><em>Scores de vitesse sur les sites WordPress populaires<\/em><\/span><\/figcaption><\/figure>\n<p>Qui plus est, la majorit\u00e9 de ces sites utilisaient WordPress. Il pose la question, comment pouvez-vous faire un site WordPress plus rapide?<\/p>\n<p>L&#8217;un des plus grands avantages de l&#8217;exploitation d&#8217;un site WordPress est l&#8217;acc\u00e8s aux millions de plugins qui tirent parti de la connaissance collective des d\u00e9veloppeurs du monde entier. Alors, quels plugins sont actuellement disponibles pour les \u00e9diteurs qui pourraient les aider avec la vitesse abyssale site? Et, quels th\u00e8mes et outils peuvent \u00eatre utilis\u00e9s pour augmenter les scores de vitesse globale du site?<\/p>\n<p><!--more--><\/p>\n<p><strong>Regardez-moi marcher \u00e0 travers juste les plugins sur Ezoic Explique ci-dessous &#8211; ou lire le reste de cet article pour tous les d\u00e9tails.<\/strong><\/p>\n<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ce_que_nous_savons_sur_WordPress_et_les_scores_de_vitesse_du_site\"><\/span><strong>Ce que nous savons sur WordPress et les scores de vitesse du site<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les sites Web WordPress sont parfaits pour les \u00e9diteurs parce qu&#8217;ils sont faciles \u00e0 configurer, simples \u00e0 g\u00e9rer, et donnent acc\u00e8s \u00e0 un grand nombre de fonctionnalit\u00e9s avanc\u00e9es gr\u00e2ce \u00e0 des plugins qui permettent aux webmasters de contourner le codage ou d&#8217;apprendre \u00e0 int\u00e9grer leur site avec des Ressources.<\/p>\n<p>La conception modulaire de WordPress laisse \u00e9galement ouvert \u00e0 un certain nombre de d\u00e9fis potentiels avec la vitesse du site.<\/p>\n<p>Si vous n&#8217;avez pas un solide fond de r\u00e9seauou de d\u00e9veloppement, passer au peigne fin la complexit\u00e9 de ce qui ralentit un site Web peut \u00eatre intimidant.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7356\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T140659.473-min-1024x533.png\" alt=\"vitesse du site web wordpress\" width=\"932\" height=\"485\"><\/p>\n<p><strong>Dans WordPress, tous ces \u00e9l\u00e9ments peuvent potentiellement avoir un impact dramatique sur la vitesse de votre site Web :<\/strong><\/p>\n<ul>\n<li>Le th\u00e8me que vous s\u00e9lectionnez<\/li>\n<li>Quels plugins vous utilisez<\/li>\n<li>H\u00e9bergement, utilisation d&#8217;un CDN, mise en cache et application des r\u00e8gles \u00e0 votre cache<\/li>\n<li>Comment vous g\u00e9rez le code CSS et JS externe<\/li>\n<li>Quelles sont les ressources externes appel\u00e9es en raison des int\u00e9grations avec votre site (outils de partage social, annonces, newsletters)<\/li>\n<\/ul>\n<p>Ci-dessous, je vais passer en revue quelques d\u00e9tails de quels plugins peuvent acc\u00e9l\u00e9rer votre site Web, comment mieux les configurer, comment mieux g\u00e9rer les th\u00e8mes, et comment les \u00e9diteurs Ezoic peuvent s&#8217;assurer qu&#8217;ils tirent parti de la puissance de la plate-forme Ezoic pour rendre leurs sites plus rapides ainsi.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quels_themes_WordPress_sont_les_plus_lents\"><\/span><strong>Quels th\u00e8mes WordPress sont les plus lents?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Changer votre th\u00e8me WordPress peut \u00eatre long et potentiellement pr\u00e9judiciable aux exp\u00e9riences des utilisateurs<a href=\"https:\/\/blog.ezoic.com\/3-ways-to-improve-website-performance-in-2019-without-a-redesign\/\" target=\"_blank\" rel=\"noopener\">(m\u00eame si vous pensez que tout sur le site &#8220;regarde&#8221; mieux<\/a>). Ainsi, avant de sortir et de changer votre th\u00e8me WordPress \u00e0 l&#8217;un des plus rapides \u00e9num\u00e9r\u00e9s ci-dessous, vous voudrez peut-\u00eatre d&#8217;abord voir si le v\u00f4tre est sur la liste des th\u00e8mes &#8220;lents&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7361 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/karuna-wordpress-template-free-download-dshno-o-min.jpg\" alt=\"th\u00e8mes wordpress les plus lents\" width=\"842\" height=\"713\"><\/p>\n<p><strong>Connu pour \u00eatre lent th\u00e8mes WordPress:<\/strong><\/p>\n<ul>\n<li>Le7<\/li>\n<li>Th\u00e8meX<\/li>\n<li>Vitrine<\/li>\n<li>Karuna<\/li>\n<li>Ixion<\/li>\n<li>d\u00e9pit<\/li>\n<li>R\u00e9\u00e9quilibrer<\/li>\n<li>Lodestar<\/li>\n<li>[Th\u00e8mes construits sur mesure qui n&#8217;ont pas \u00e9t\u00e9 con\u00e7us avec la vitesse \u00e0 l&#8217;esprit]<\/li>\n<\/ul>\n<p>La chose la plupart d&#8217;entre eux ont en commun, c&#8217;est qu&#8217;ils comprennent beaucoup de composants suppl\u00e9mentaires int\u00e9gr\u00e9s. Souvent, ces extras sont pour rendre le site plus facile \u00e0 construire sur le front-end ou inclure des fonctionnalit\u00e9s CSS \u00e9tranges ou uniques.<\/p>\n<p>Dans la plupart des cas, les probl\u00e8mes avec la vitesse du <strong>site sur ces th\u00e8mes peuvent \u00eatre presque totalement att\u00e9nu\u00e9s<\/strong> si vous tirez parti des meilleures pratiques autour de chargement <a href=\"\/?p=6538\">CSS <\/a>et <a href=\"\/?p=16284\">WordPress image servant<\/a> aux c\u00f4t\u00e9s de certaines de nos autres informations ci-dessous.<\/p>\n<p>De fa\u00e7on r\u00e9aliste, la diff\u00e9rence entre un th\u00e8me rapide et un th\u00e8me lent n&#8217;est g\u00e9n\u00e9ralement pas tr\u00e8s dramatique. La vitesse du site d\u00e9pend davantage de la fa\u00e7on dont le reste du site est configur\u00e9 (comment la mise en cache, le CSS et jS, et les ressources externes sont utilis\u00e9s).<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quels_themes_WordPress_sont_les_plus_rapides\"><\/span><strong>Quels th\u00e8mes WordPress sont les plus rapides?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Tout comme indiqu\u00e9 ci-dessus, il suffit de changer votre th\u00e8me WordPress peut ne pas offrir d&#8217;avantages significatifs de vitesse du site. Si vous avez d&#8217;autres probl\u00e8mes majeurs qui affectent la vitesse du site, le th\u00e8me peut ne pas \u00eatre un facteur majeur dans les scores de vitesse de page plus lent.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7406 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/grille-personal-blog-wordpress-theme-bbfg3-o-min-1024x867.jpg\" alt=\"th\u00e8me rapide de wordpress de grille\" width=\"868\" height=\"735\"><\/p>\n<p><strong>Voici quelques-uns des th\u00e8mes WordPress les plus rapides et connus :<\/strong><\/p>\n<ul>\n<li>Skylar<\/li>\n<li>grillage<\/li>\n<li>Vingt &#8220;Quinze&#8221;, &#8220;Quatorze&#8221;, etc. (th\u00e8me WP par d\u00e9faut)<\/li>\n<li>GeneratePress (en)<\/li>\n<li>Divi (lorsqu&#8217;il est configur\u00e9 correctement)<\/li>\n<li>OceanWP (en anglais seulement)<\/li>\n<li>vid\u00e9oblog<\/li>\n<\/ul>\n<p>Il ya probablement beaucoup plus que le score presque aussi \u00e9lev\u00e9 lorsqu&#8217;il est mis en \u0153uvre avec un peu plus de contenu et d&#8217;images. Si vous ne voyez pas votre th\u00e8me sur l&#8217;une ou l&#8217;autre liste, il peut ne pas \u00eatre utile de passer \u00e0 moins que vous avez r\u00e9ussi \u00e0 g\u00e9rer tout le reste du mat\u00e9riel ci-dessous, ou dans nos messages pass\u00e9s sur la <a href=\"\/?p=5531\">vitesse du site WordPress<\/a>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quels_plugins_peuvent_etre_utilises_pour_rendre_un_site_Web_plus_rapide\"><\/span><strong>Quels plugins peuvent \u00eatre utilis\u00e9s pour rendre un site Web plus rapide?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Il ya des tonnes de plugins dans l&#8217;\u00e9cosyst\u00e8me de plugin WordPress qui vantent diverses fonctionnalit\u00e9s con\u00e7ues pour rendre un site Plus rapide. Malheureusement, certains d&#8217;entre eux vont effectivement ralentir votre site encore plus si elles ne sont pas impl\u00e9ment\u00e9es correctement &#8211; ou pire &#8211; briser votre site Web compl\u00e8tement sur le front-end.<\/p>\n<p>Ci-dessous, sont plugins j&#8217;ai examin\u00e9 dans la vid\u00e9o en haut de ce blog. Je marche \u00e0 travers la fa\u00e7on de configurer chacun d&#8217;eux. Si vous \u00eates un utilisateur Ezoic, certains d&#8217;entre eux peuvent ne pas \u00eatre enti\u00e8rement compatibles avec votre configuration Ezoic. Cela dit, l&#8217;application de vitesse du <a href=\"\/?page_id=26969\">site Ezoic<\/a> peut prendre beaucoup de cela et le rendre beaucoup plus facile que de configurer des plugins (il ya de nouvelles fonctionnalit\u00e9s presque chaque semaine pour simplifier son fonctionnement).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7366 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T144344.422-min-1024x559.png\" alt=\"meilleurs plugins wordpress pour la vitesse du site\" width=\"859\" height=\"469\"><\/p>\n<p><strong>Ces plugins fonctionnent le mieux pour acc\u00e9l\u00e9rer les sites WordPress:<\/strong><\/p>\n<ul>\n<li>Nettoyage des actifs Pro<\/li>\n<li>WP-Rocket (en anglais seulement)<\/li>\n<li>WP Disable<\/li>\n<li>ShortPixel (en)<\/li>\n<\/ul>\n<p>Il ya beaucoup plus de plugins que vous pourriez utiliser. Ceux-ci vous permettent simplement d&#8217;\u00e9liminer et d&#8217;aborder certaines des<em>pportunities<\/em> O les plus courantes pr\u00e9sent\u00e9es par Pagespeed Insights de Google.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7371 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T144515.897-min.png\" alt=\"r\u00e9soudre les probl\u00e8mes de score de perspicacit\u00e9 pagespeed\" width=\"688\" height=\"287\"><\/p>\n<p><strong>par exemple:<\/strong><\/p>\n<ul>\n<li>Diff\u00e9rer cSS inutilis\u00e9 et Javascript<\/li>\n<li>\u00c9liminer les ressources de blocage de rendu<\/li>\n<li>Diff\u00e9rer les images hors \u00e9cran<\/li>\n<li>Servir des images dans des formats next-gen<\/li>\n<li>Supprimer le CSS inutilis\u00e9<\/li>\n<li>Encoder efficacement les images<\/li>\n<li>et plus encore&#8230;<\/li>\n<\/ul>\n<p>Un grand nombre de ces plugins ont une bonne quantit\u00e9 de fonctionnalit\u00e9s et de capacit\u00e9s qui se chevauchent; cependant, chacun fournit plusieurs fonctionnalit\u00e9s uniques qui donnent webmasters la possibilit\u00e9 de main-tune leur vitesse de site Web.<\/p>\n<p><strong>Malheureusement, il suffit d&#8217;allumer ces plugins ne r\u00e9soudra pas vos probl\u00e8mes<\/strong>de vitesse du site . Nous aurons besoin de les utiliser correctement et chaque site Web aura des tol\u00e9rances diff\u00e9rentes pour ce qui peut \u00eatre activ\u00e9 sur ces outils (ce qui signifie que certaines fonctionnalit\u00e9s sur ces plugins peuvent causer votre site \u00e0 afficher incorrectement).<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_utiliser_WP-Rocket_pour_rendre_votre_site_web_plus_rapide\"><\/span><strong>Comment utiliser WP-Rocket pour rendre votre site web plus rapide<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-7381 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T145111.313-min-1024x589.png\" alt=\"wp-fus\u00e9e et vitesse du site\" width=\"1024\" height=\"589\"><\/p>\n<p>WP-Rocket est un plugin de mise en cache qui vous donne un tr\u00e8s grand contr\u00f4le sur la mise en cache du site Web, l&#8217;optimisation des fichiers et le chargement des m\u00e9dias. Bon nombre des possibilit\u00e9s d&#8217;am\u00e9liorer la vitesse du site \u00e9num\u00e9r\u00e9es dans le rapport Pagespeed Insights peuvent souvent \u00eatre corrig\u00e9es avec de meilleures r\u00e8gles de mise en cache et de chargement de fichiers.<\/p>\n<p><em>Note: WP-Rocket sert le m\u00eame but que beaucoup d&#8217;autres prises de caching populaires et &#8220;optimisation&#8221; plugins. Cela comprend, mais n&#8217;est pas limit\u00e9 \u00e0 W3 cache, WP Super Cache, WP Fastest Cache, Hyper Cache, et beaucoup plus. Il sera probablement en conflit avec eux, sauf si vous les d\u00e9sactiver apr\u00e8s avoir configurant WP-Rocket.<\/em><\/p>\n<p>Dans ma vid\u00e9o en haut, je marche \u00e0 travers une fa\u00e7on de configurer conservateur ce plugin. J&#8217;ai inclus un GIF ci-dessous que les commentaires de cette mise en place qui pourrait aider. Mais, si vous voulez plus de direction sur le fait de ce plugin de travail pour vous, je vous recommande de regarder cette partie de ma vid\u00e9o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7386 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/ezgif-1-12c34fab3272.gif\" alt=\"faire mon site web wordpress rapide\" width=\"660\" height=\"344\"><\/p>\n<p>La seule chose que je vais ajouter que je n&#8217;ai pas inclus dans la vid\u00e9o, est de savoir comment tirer parti du pr\u00e9-chargement.<\/p>\n<p>Votre site fera souvent des appels \u00e0 des ressources externes (par exemple Facebook.com charger leur logo pour le widget de partage social). Le pr\u00e9-chargement vous permet d&#8217;acc\u00e9l\u00e9rer ce processus dans la plupart des cas.<\/p>\n<p>L&#8217;un des points les plus faciles de pr\u00e9-chargement est simplement de permettre \u00e0 WP-Rocket de pr\u00e9charger des pages pour les visiteurs en fonction de votre carte de site. C&#8217;est simple. Sous <em>Pr\u00e9chargement<\/em>, il suffit d&#8217;entrer votre URL sitemap. Il est g\u00e9n\u00e9ralement y<em>ourwebsite.com\/sitemap.xml.<\/em> Yoast ou un autre plugin peut le cr\u00e9er pour vous.<\/p>\n<p>Vous pouvez \u00e9galement utiliser l&#8217;outil phare de Google Chrome pour obtenir une liste des URL externes que vous devez mettre dans wp-Rockets <em>Prefetch DNS Requests <\/em>zone sous <em>Preloading<\/em>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-7396 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T151121.753-min-1024x424.png\" alt=\"trouver des demandes de pr\u00e9-fetch dns\" width=\"1024\" height=\"424\"><\/p>\n<p><strong>Comment le faire:<\/strong><\/p>\n<ol>\n<li>Rendez-vous sur votre site Web sur un navigateur Chrome<\/li>\n<li>Cliquez \u00e0 droite et s\u00e9lectionnez \u00c9l\u00e9ments d&#8217;inspection<\/li>\n<li>S\u00e9lectionnez &#8221; audit &#8221; dans le menu du haut<\/li>\n<li>S\u00e9lectionnez &#8220;Performance&#8221; et ex\u00e9cutez l&#8217;audit<\/li>\n<li>Trouvez les \u00ab demandes cl\u00e9s de pr\u00e9charge \u00bb et cliquez sur cette case<\/li>\n<li>Ne pas copier\/coller ces URL telles que sp\u00e9cifi\u00e9es dans la partie pr\u00e9fetch de WP-Rocket<\/li>\n<\/ol>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7401 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T151440.327.png\" alt=\"temps de chargement de page plus rapide dans wordpress\" width=\"827\" height=\"247\"><\/p>\n<p><em><strong>WP-Rocket est compatible avec Ezoic. <\/strong><\/em>Lorsqu&#8217;ils sont utilis\u00e9s correctement avec l&#8217;int\u00e9gration des nameservers Ezoic, et l&#8217;application de mise en cache d&#8217;Ezoic, les sites peuvent souvent voir des am\u00e9liorations consid\u00e9rables dans la vitesse du site Web.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_utiliser_WP_Disable_pour_rendre_votre_site_web_plus_rapide\"><\/span><strong>Comment utiliser WP Disable pour rendre votre site web plus rapide<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-7411 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T151759.369-min-1024x455.png\" alt=\"plugins wordpress qui rendent le blog plus rapide\" width=\"1024\" height=\"455\"><\/p>\n<p>WP Disable est un plugin qui semble dangereux. Et bien qu&#8217;il pourrait \u00eatre, il utilise un langage tr\u00e8s simple et de bonnes descriptions pour vous aider \u00e0 mieux comprendre ses capacit\u00e9s. Dans la plupart des cas, les \u00e9diteurs WordPress ont un certain nombre de fichiers inutiles et le code qui peuvent \u00eatre \u00e9limin\u00e9s de charges de page.<\/p>\n<p>Cela aidera avec le &#8220;render-blocking&#8230;&#8221; et &#8220;inutilis\u00e9&#8230;&#8221; recommandations des mesures de vitesse du site. Pour ce faire, nous avons vraiment seulement besoin d&#8217;utiliser les onglets mis en \u00e9vidence ci-dessus dans l&#8217;outil. WP Disable nous donne quelques fonctionnalit\u00e9s qui peuvent nous permettre d&#8217;optimiser l&#8217;exc\u00e8s de code que les autres plugins ne sont pas.<\/p>\n<p>Voici quelques images de ma configuration ci-dessous. Vous pouvez vous sentir libre de jouer avec les param\u00e8tres vous-m\u00eame pour voir lesquels peuvent ou peuvent ne pas \u00eatre bon pour votre site.<\/p>\n<p>J&#8217;appr\u00e9cie vraiment la capacit\u00e9 des outils pour me permettre de charger de lourdes polices externes asynchronement et de g\u00e9rer la fa\u00e7on dont toutes mes polices se chargent. Souvent, les polices sont un probl\u00e8me central avec la vitesse du site puisque la plupart des sites utilisent des polices Google ou une autre police externe. Ceux-ci peuvent devenir assez lourds et causer un ralentissement majeur du site.<\/p>\n<figure id=\"attachment_7416\" aria-describedby=\"caption-attachment-7416\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7416 size-large\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T151720.517-min-1024x701.png\" alt=\"configuration de vitesse du site\" width=\"1024\" height=\"701\"><figcaption id=\"caption-attachment-7416\" class=\"wp-caption-text\"><em>Cette configuration peut ne pas \u00eatre id\u00e9ale pour tous les sites, mais l&#8217;optimisation d&#8217;une combinaison de fonctionnalit\u00e9s pour am\u00e9liorer les temps de charge de police est un grand avantage \u00e0 l&#8217;aide de ce plugin.<\/em><\/figcaption><\/figure>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-7421 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T152359.484-1024x469.png\" alt=\"meilleur plugin pour la vitesse du site\" width=\"1024\" height=\"469\"><\/p>\n<p><strong>WP Disable est compatible avec Ezoic<\/strong>, mais bient\u00f4t l&#8217;application de vitesse du site Ezoic peut avoir la possibilit\u00e9 de mieux configurer certaines de ces choses automatiquement.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Comment_utiliser_Asset_CleanUp_Pro_pour_rendre_votre_site_Web_plus_rapide\"><\/span><strong>Comment utiliser Asset CleanUp Pro pour rendre votre site Web plus rapide<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-7376 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T144730.884-min-1024x424.png\" alt=\"plugin pour la vitesse du site\" width=\"1024\" height=\"424\"><\/p>\n<p>Asset CleanUp Pro (ACP) offre beaucoup de fonctionnalit\u00e9s gratuitement, mais dans de nombreux cas, vous voudrez payer le tr\u00e8s petit montant dont ils ont besoin pour passer \u00e0 leur version premium. La version Premium offre juste un contr\u00f4le plus granulaire des \u00e9l\u00e9ments de JS et CSS que vous voudrez peut-\u00eatre mieux contr\u00f4ler sur votre site Web.<\/p>\n<p>Dans ACP, vous pouvez ignorer la plupart des param\u00e8tres principaux, ce sont des choses que nous pouvons mieux aborder avec les autres plugins. Le principal avantage d&#8217;AssetCleanUp est que nous pouvons identifier des fichiers sp\u00e9cifiques \u00e0 partir de nos rapports Pagespeed Insights que nous pouvons vouloir aborder sur l&#8217;ensemble du site, ou tout simplement sur des pages sp\u00e9cifiques &#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7426 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T152851.378-min.png\" alt=\"google pagespeed insights (en)\" width=\"877\" height=\"648\"><\/p>\n<p><strong>Exemple de la fa\u00e7on d&#8217;utiliser Asset CleanUp :<\/strong><\/p>\n<ol>\n<li>Ex\u00e9cuter un rapport Google Pagespeed Insights<\/li>\n<li>Cliquez pour ouvrir les r\u00e9sultats pour &#8220;\u00c9liminer les ressources de blocage de rendu&#8221; et &#8220;Diff\u00e9rer le CSS inutilis\u00e9&#8221;\n<ul>\n<li>Ceux-ci vous donneront une liste de fichiers et d&#8217;URL qui m\u00e8nent \u00e0 des temps de chargement plus longs<\/li>\n<\/ul>\n<\/li>\n<li>Maintenant, allez \u00e0 ACP dans votre tableau de bord WP<\/li>\n<li>Cliquez sur <em>CSS et Javascript Load Manager <\/em>en haut<\/li>\n<li>Maintenant, vous pouvez naviguer vers des pages que vous pouvez \u00eatre en mesure de d\u00e9sactiver des fichiers sp\u00e9cifiques sur<\/li>\n<li>Maintenant, lors de l&#8217;ouverture de pages ou de publications, vous trouverez la possibilit\u00e9 de reporter, asynch, ou d\u00e9charger des fichiers sp\u00e9cifiques ou des plugins \u00e0 travers les pages, les messages ou les URL simples\n<ul>\n<li>Dans mon exemple ci-dessous, j&#8217;utilise le widget de partage social et les plugins MailChimp comme fichiers qui causent le blocage de rendu qui peut \u00eatre facilement d\u00e9charg\u00e9 sur n&#8217;importe quel &#8220;pages&#8221; sur mon site WordPress. Les deux plugins ne sont n\u00e9cessaires que sur mes articles, pas sur tout mon site. J&#8217;ai d\u00e9charg\u00e9 ces fichiers sur tous les types de pages sans nuire \u00e0 mon site.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7432 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/ezgif-1-782804f54215.gif\" alt=\"diff\u00e9rer le CSS inutilis\u00e9\" width=\"601\" height=\"324\"><\/p>\n<p>Chaque site devra \u00eatre pointilleux sur les r\u00e8gles qu&#8217;ils ont fix\u00e9es sur chaque fichier respectif. Le rapport pagespeed peut \u00eatre un guide, mais souvent vous ne pouvez pas supprimer ou reporter tous les fichiers qu&#8217;il r\u00e9pertorie pour assurer la fonction appropri\u00e9e du site.<\/p>\n<p>ACP offre un mode de test que vous pouvez utiliser afin que vous puissiez vous assurer que votre site Web reste op\u00e9rationnel pendant que vous exp\u00e9rimentez.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Utilisation_de_ShortPixel_pour_servir_des_images_dans_des_formats_next-gen\"><\/span><strong>Utilisation de ShortPixel pour servir des images dans des formats next-gen<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Je suis entr\u00e9 dans les d\u00e9tails profonds de la fa\u00e7on dont les sites Web WordPress peuvent facilement utiliser ShortPixel pour servir des images dans des formats next-gen et compresser toutes leurs images dans un blog pr\u00e9c\u00e9dent.<\/p>\n<p><a href=\"\/?p=16284\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6221 size-large\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-04-10T101428.692-1024x326.png\" alt=\"servir des images dans des formats next-gen pour des aper\u00e7us pagespeed\" width=\"1024\" height=\"326\"><\/a><\/p>\n<p>Je recommande vivement la lecture de <a href=\"\/?p=16284\">ce blog si vous voyez &#8220;Encoder efficacement des images&#8221; ou &#8220;Servir des images dans des formats next-gen&#8221;<\/a> sur Pagespeed Insight rapports.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Utilisation_dEzoic_pour_simplifier_la_vitesse_du_site_WordPress\"><\/span><strong>Utilisation d&#8217;Ezoic pour simplifier la vitesse du site WordPress<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>L&#8217;application de vitesse du site d&#8217;Ezoic ajoute rapidement un certain nombre de fonctions et de fonctionnalit\u00e9s qui rendent un grand nombre de ces plugins inutiles si vous \u00eates un \u00e9diteur Ezoic.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7437 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T155015.288-min-1024x633.png\" alt=\"am\u00e9liorer la vitesse du site Web\" width=\"998\" height=\"617\"><\/p>\n<p><strong>Actuellement, vous pouvez utiliser l&#8217;application de vitesse du site dans l&#8217;App Store Ezoic pour :<\/strong><\/p>\n<ul>\n<li>Supprimer le CSS inutilis\u00e9<\/li>\n<li>Optimiser la livraison de CSS de blocage de rendu<\/li>\n<li>Chargeuse paresseuse ou report de la charge d&#8217;image pour les images hors \u00e9cran<\/li>\n<\/ul>\n<p>De nouvelles fonctionnalit\u00e9s qui vous permettent de faire des exceptions ont \u00e9t\u00e9 ajout\u00e9es et de simplifier une grande partie de ce que j&#8217;ai montr\u00e9 ci-dessus en utilisant le plugin Asset CleanUp.<\/p>\n<p>En fait, l&#8217;application Ezoic sera probablement beaucoup plus facile \u00e0 utiliser et plus efficace que de le faire manuellement. Ainsi, si vous \u00eates un utilisateur Ezoic, vous pouvez \u00eatre en mesure d&#8217;ignorer la configuration du plugin ACP.<\/p>\n<p>Comme mentionn\u00e9 ci-dessus, Ezoic (et l&#8217;application de cachrage Ezoic) peut offrir quelques coups de pouce assez grand \u00e0 la vitesse si la cachage est coordonn\u00e9 correctement avec vos plugins de caching. Il est important de s&#8217;assurer que cela fonctionne correctement sur votre site. Si vous entrez dans Big Data Analytics \u00e0 partir de votre tableau de bord &gt; Ezoic Site Speed &gt; Ezoic Caching, vous pouvez voir si la mise en cache Ezoic fonctionne.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-7442 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/image-29-1024x521.png\" alt=\"caching \u00e9zo\u00efque\" width=\"1024\" height=\"521\"><\/p>\n<p>Si la majorit\u00e9 sont &#8220;off&#8221; ou &#8220;manquer&#8221; les r\u00e8gles sur le cache de votre site peut \u00eatre l&#8217;emportesur sur certains des avantages d&#8217;Ezoic. Assurez-vous que vous n&#8217;avez pas de p\u00e9riodes de mise en cache excessivement courtes activ\u00e9es sur votre site ou contactez support@ezoic.com si vous ne pouvez pas comprendre comment le configurer correctement.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Les_sites_ezoiques_sont_en_moyenne_plus_rapides_que_les_sites_en_haut\"><\/span><strong>Les sites \u00e9zo\u00efques sont en moyenne plus rapides que les sites en haut<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Lorsqu&#8217;il est configur\u00e9 correctement, le site Moyen Ezoic WordPress fonctionne g\u00e9n\u00e9ralement mieux que l&#8217;original et mieux que les sites \u00e9num\u00e9r\u00e9s en haut.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7453 aligncenter\" src=\"https:\/\/www.ezoic.com\/fr-lang\/wp-content\/uploads\/2021\/08\/download-2019-05-01T162011.018-min.png\" alt=\"vitesse du site Ezoic\" width=\"843\" height=\"534\"><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Rendre_votre_site_Web_WordPress_rapide\"><\/span><strong>Rendre votre site Web WordPress rapide<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En utilisant ces plugins et outils, vous devriez \u00eatre en mesure de rendre votre site plus rapide. Je recommande fortement ces blogs ainsi si vous \u00eates dans la chasse pour rendre votre site rapide.<\/p>\n<ul>\n<li><a href=\"\/?p=5531\">Comment faire votre site WordPress rapide<\/a><\/li>\n<li><a href=\"\/?p=16284\">Comment servir des images dans des formats next-gen<\/a><\/li>\n<\/ul>\n<p>Enfin, si vous avez des questions sur la vitesse de votre site s&#8217;il vous pla\u00eet laissez-les ci-dessous. Je ferai de mon mieux pour vous donner des conseils.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section bb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221;][et_pb_row admin_label=&#8221;row&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; background_size=&#8221;initial&#8221; _builder_version=&#8221;3.21.4&#8243; z_index_tablet=&#8221;500&#8243;] Quels plugins WordPress et th\u00e8mes peuvent acc\u00e9l\u00e9rer votre site Web? Continuez-vous \u00e0 recevoir des rapports pagespeed qui montrent que votre site Web pourrait \u00eatre plus rapide? Vous et tous ceux qui poss\u00e8dent un site Web. En analysant les scores mobiles Pagespeed Insights&hellip; <a class=\"more-link\" href=\"https:\/\/wp.ezoic.com\/fr-lang\/quels-plugins-et-themes-wordpress-peuvent-accelerer-votre-site-web\/\">Continue reading <span class=\"screen-reader-text\">Quels plugins WordPress et th\u00e8mes peuvent acc\u00e9l\u00e9rer votre site Web?<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[9],"tags":[8],"class_list":["post-270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infrastructure-du-siteweb-amp-optimisation","tag-fr","entry"],"_links":{"self":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts\/270"}],"collection":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/comments?post=270"}],"version-history":[{"count":0,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/posts\/270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/media\/291"}],"wp:attachment":[{"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/media?parent=270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/categories?post=270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ezoic.com\/fr-lang\/wp-json\/wp\/v2\/tags?post=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}